{"id":11715,"date":"2022-08-24T11:51:19","date_gmt":"2022-08-24T09:51:19","guid":{"rendered":"https:\/\/enaw.ch\/klimaschutz-und-energieeffizienz-im-kanton-waadt\/"},"modified":"2024-07-19T14:36:14","modified_gmt":"2024-07-19T12:36:14","slug":"protezione-del-clima-ed-efficienza-energetica-nel-cantone-di-vaud","status":"publish","type":"page","link":"https:\/\/enaw.ch\/it\/protezione-del-clima-ed-efficienza-energetica-nel-cantone-di-vaud","title":{"rendered":"Protezione del clima ed efficienza energetica nel Cantone di Vaud"},"content":{"rendered":"\n                    <div class=\"default-page-title\">\n                <h1 class=\"margin-bottom-0\">RISPARMI NEL CANTON VAUD<\/h1>\n            <\/div>\n        \n\n\n\n            <section class=\"running-numbers running-numbers-6a5718c2a427f blue-light-bg scrollMagic-block visibleInBackend\" data-uid=\"6a5718c2a4283\">\n            <div class=\"container-main\">\n                <div class=\"running-numbers-content\">\n\n                                            <div class=\"running-number-block\">\n                            <p class=\"running-number text-blue margin-bottom-0\" id=\"running-number-6a5718c2a427f-1\">51903<\/p>\n                            <p class=\"running-number-title text-blue margin-bottom-0\">tonnellate di CO<sub>2<\/sub> ridotte<\/p>\n                        <\/div>\n                                            <div class=\"running-number-block\">\n                            <p class=\"running-number text-blue margin-bottom-0\" id=\"running-number-6a5718c2a427f-2\">364187<\/p>\n                            <p class=\"running-number-title text-blue margin-bottom-0\">di megawattora di energia risparmiati<\/p>\n                        <\/div>\n                                            <div class=\"running-number-block\">\n                            <p class=\"running-number text-blue margin-bottom-0\" id=\"running-number-6a5718c2a427f-3\">72<\/p>\n                            <p class=\"running-number-title text-blue margin-bottom-0\">milioni di franchi risparmiati<\/p>\n                        <\/div>\n                    \n                <\/div>\n\n                            <\/div>\n\n            \n            <script>\n                jQuery( function( $ ) {\n                    const running_numbers_el = $('.running-numbers.running-numbers-6a5718c2a427f');\n                    let running_numbers_play_animation_6a5718c2a427f = false;\n\n                    run_numbers();\n\n                    $(window).scroll(function(event){\n                        run_numbers();\n                    });\n\n                    function run_numbers(){\n                        scrollHeight = $(this).scrollTop();\n\n                        if(scrollHeight > running_numbers_el.offset().top - $(window).height() + 150 && !running_numbers_play_animation_6a5718c2a427f){\n                            running_numbers_play_animation_6a5718c2a427f = true;\n\n                                                        runningNumbers('running-number-6a5718c2a427f-1', 0, 51903, 2000, 1);\n                                                        runningNumbers('running-number-6a5718c2a427f-2', 0, 364187, 2000, 2);\n                                                        runningNumbers('running-number-6a5718c2a427f-3', 0, 72, 2000, 3);\n                                                    }\n                    }\n                });\n            <\/script>\n        <\/section>\n    \n\n\n\n            <section class=\"running-numbers running-numbers-6a5718c2a4445 blue-light-bg scrollMagic-block visibleInBackend\" data-uid=\"6a5718c2a4447\">\n            <div class=\"container-main\">\n                <div class=\"running-numbers-content\">\n\n                                            <div class=\"running-number-block\">\n                            <p class=\"running-number text-blue margin-bottom-0\" id=\"running-number-6a5718c2a4445-1\">358<\/p>\n                            <p class=\"running-number-title text-blue margin-bottom-0\">partecipano grandi consumatori<\/p>\n                        <\/div>\n                                            <div class=\"running-number-block\">\n                            <p class=\"running-number text-blue margin-bottom-0\" id=\"running-number-6a5718c2a4445-2\">872<\/p>\n                            <p class=\"running-number-title text-blue margin-bottom-0\">partecipano stabilimenti<\/p>\n                        <\/div>\n                    \n                <\/div>\n\n                                    <p class=\"text-notice margin-bottom-0\">Impatto delle misure nel 2022<\/p>\n                            <\/div>\n\n            \n            <script>\n                jQuery( function( $ ) {\n                    const running_numbers_el = $('.running-numbers.running-numbers-6a5718c2a4445');\n                    let running_numbers_play_animation_6a5718c2a4445 = false;\n\n                    run_numbers();\n\n                    $(window).scroll(function(event){\n                        run_numbers();\n                    });\n\n                    function run_numbers(){\n                        scrollHeight = $(this).scrollTop();\n\n                        if(scrollHeight > running_numbers_el.offset().top - $(window).height() + 150 && !running_numbers_play_animation_6a5718c2a4445){\n                            running_numbers_play_animation_6a5718c2a4445 = true;\n\n                                                        runningNumbers('running-number-6a5718c2a4445-1', 0, 358, 2000, 1);\n                                                        runningNumbers('running-number-6a5718c2a4445-2', 0, 872, 2000, 2);\n                                                    }\n                    }\n                });\n            <\/script>\n        <\/section>\n    \n\n\n\n    <section class=\"title-text-button-block  title-text-button-block-6a5718c2a46e9 block-paddings \" id=\"\">\n        <div class=\"container-main\">\n                                        <div class=\"title-block title-block-6a5718c2a4733 scrollMagic-block visibleInBackend\" data-uid=\"6a5718c2a4734\">\n        \n                    <h2>L&#8217;efficienza energetica<br>aumenta,<br>l&#8217;intensit\u00e0 di CO<sub>2<\/sub> diminuisce<\/h2>\n            <\/div>\n\n            <div class=\"narrow-container\">\n                                    <div class=\"description-block scrollMagic-block visibleInBackend\" data-uid=\"6a5718c2a4737\">\n                        <p>Grazie alle misure attuate dal 2013, le aziende del Cantone di Vaud consumano 364&nbsp;187 megawattora di energia in meno. Nello stesso periodo, le aziende di Vaud sono riuscite a ridurre le emissioni di CO<sub>2<\/sub> di 51&nbsp;903 tonnellate.<\/p>\n                    <\/div>\n                \n                \n                            <\/div>\n        <\/div>\n\n            <\/section>\n\n    \n\n\n\n            <section class=\"chart-block chart-line chart-block-6a5718c2a6fb7 scrollMagic-block visibleInBackend\" data-uid=\"6a5718c2a6fbd\">\n            <div class=\"container-main\">\n                <div class=\"chart-title-block\">\n                    \n                                            <p class=\"chart-subtitle\">Efficienza energetica <\/p>\n                                    <\/div>\n\n                <div id=\"chart-6a5718c2a6fb7\"><\/div>\n            <\/div>\n\n            <script type=\"text\/javascript\">\n                let data_6a5718c2a6fb7 = JSON.parse('[{\"name\":\"Valore effettivo\",\"color\":\"#ffcc01\",\"data\":\"100.0, 99.3, 103.4, 105.4, 107.1, 108.1, 110, 111.2, 113, 113.2, 114.3, 116.3\"},{\"name\":\"Traiettoria\",\"color\":\"#07005c\",\"data\":\"100.0, 100.4, 101.1, 102, 103, 103.3, 104.1, 105.0, 106, 107, 108, 109\"}]');\n\n                data_6a5718c2a6fb7 = data_6a5718c2a6fb7.map(function(item) {\n                    const temp = item.data.split(', ').map(function(item) {\n                        return parseInt(item, 10);\n                    });\n\n                    return {\n                        name: item.name,\n                        data: temp,\n                        color: item.color,\n                    };\n                });\n\n                setTimeout(function (){\n                    Highcharts.chart('chart-6a5718c2a6fb7', {\n                        chart: {\n                            events: {\n                                load: function() {\n                                    this.series.forEach(function(series) {\n                                        series.points[series.points.length - 1].update({\n                                            dataLabels: {\n                                                enabled: true,\n                                                className: 'last-item',\n                                                format: series.yData[series.yData.length - 1] + '%',\n                                                  }\n                                        });\n                                    });\n                                }\n                            }\n                        },\n                        title: {\n                            text: '',\n                            align: 'center',\n                        },\n                        subtitle: {\n                            text: 'Efficienza energetica ',\n                            align: 'center',\n                        },\n                        credits: {\n                            enabled: false\n                        },\n                        yAxis: {\n                            title: {\n                                text: 'Efficienza energetica in %'\n                            }\n                        },\n                        legend: {\n                            layout: 'vertical',\n                            align: 'right',\n                            verticalAlign: 'middle'\n                        },\n                        plotOptions: {\n                            series: {\n                                label: {\n                                    connectorAllowed: false\n                                },\n                                pointStart: 2012                            }\n                        },\n                        series: data_6a5718c2a6fb7,\n                        responsive: {\n                            rules: [{\n                                condition: {\n                                    maxWidth: 500\n                                },\n                                chartOptions: {\n                                    legend: {\n                                        layout: 'horizontal',\n                                        align: 'center',\n                                        verticalAlign: 'bottom'\n                                    }\n                                }\n                            }]\n                        }\n                    });\n                }, 500);\n            <\/script>\n        <\/section>\n    \n\n\n\n            <section class=\"chart-block chart-line chart-block-6a5718c2a728e scrollMagic-block visibleInBackend\" data-uid=\"6a5718c2a7294\">\n            <div class=\"container-main\">\n                <div class=\"chart-title-block\">\n                    \n                                            <p class=\"chart-subtitle\">Intensit\u00e0 di CO\u2082<\/p>\n                                    <\/div>\n\n                <div id=\"chart-6a5718c2a728e\"><\/div>\n            <\/div>\n\n            <script type=\"text\/javascript\">\n                let data_6a5718c2a728e = JSON.parse('[{\"name\":\"Traiettoria\",\"color\":\"#07005c\",\"data\":\"100.0, 99.4, 98.4, 97.4, 96.1, 95, 94, 93, 91.3, 90.2, 89.1, 88\"},{\"name\":\"Valore effettivo\",\"color\":\"#ffcc01\",\"data\":\"100.0, 102, 96, 93, 91, 90, 89, 88, 87, 87, 85.1, 83.2\"}]');\n\n                data_6a5718c2a728e = data_6a5718c2a728e.map(function(item) {\n                    const temp = item.data.split(', ').map(function(item) {\n                        return parseInt(item, 10);\n                    });\n\n                    return {\n                        name: item.name,\n                        data: temp,\n                        color: item.color,\n                    };\n                });\n\n                setTimeout(function (){\n                    Highcharts.chart('chart-6a5718c2a728e', {\n                        chart: {\n                            events: {\n                                load: function() {\n                                    this.series.forEach(function(series) {\n                                        series.points[series.points.length - 1].update({\n                                            dataLabels: {\n                                                enabled: true,\n                                                className: 'last-item',\n                                                format: series.yData[series.yData.length - 1] + '%',\n                                                  }\n                                        });\n                                    });\n                                }\n                            }\n                        },\n                        title: {\n                            text: '',\n                            align: 'center',\n                        },\n                        subtitle: {\n                            text: 'Intensit\u00e0 di CO\u2082',\n                            align: 'center',\n                        },\n                        credits: {\n                            enabled: false\n                        },\n                        yAxis: {\n                            title: {\n                                text: 'Intensit\u00e0 di CO\u2082 (BS) in %'\n                            }\n                        },\n                        legend: {\n                            layout: 'vertical',\n                            align: 'right',\n                            verticalAlign: 'middle'\n                        },\n                        plotOptions: {\n                            series: {\n                                label: {\n                                    connectorAllowed: false\n                                },\n                                pointStart: 2012                            }\n                        },\n                        series: data_6a5718c2a728e,\n                        responsive: {\n                            rules: [{\n                                condition: {\n                                    maxWidth: 500\n                                },\n                                chartOptions: {\n                                    legend: {\n                                        layout: 'horizontal',\n                                        align: 'center',\n                                        verticalAlign: 'bottom'\n                                    }\n                                }\n                            }]\n                        }\n                    });\n                }, 500);\n            <\/script>\n        <\/section>\n    \n\n\n\n    <section class=\"title-text-button-block  title-text-button-block-6a5718c2a74e8 block-paddings blue-light-bg\" id=\"\">\n        <div class=\"container-main\">\n                                        <div class=\"title-block title-block-6a5718c2a7516 scrollMagic-block visibleInBackend\" data-uid=\"6a5718c2a7517\">\n        \n                    <h2>Misure redditizie come chiave di successo<\/h2>\n            <\/div>\n\n            <div class=\"narrow-container\">\n                                    <div class=\"description-block scrollMagic-block visibleInBackend\" data-uid=\"6a5718c2a751a\">\n                        <p>Ogni azienda attua un catalogo di misure individuale. I progetti devono essere redditizie: Dietro ogni kilowattora e tonnellata di CO<sub>2<\/sub> risparmiata si celano tempi di payback documentati. Nel Cantone di Vaud, le misure nei seguenti settori sono finora i principali fattori di protezione del clima e di efficienza energetica dell&#8217;economia:<\/p>\n                    <\/div>\n                \n                \n                            <\/div>\n        <\/div>\n\n            <\/section>\n\n    \n\n\n\n            <section class=\"running-numbers-cards blue-light-bg scrollMagic-block visibleInBackend\" data-uid=\"6a5718c2a7eb1\">\n            <div class=\"container-main\">\n                <div class=\"running-numbers-cards-content\">\n\n                                                            \n                    <div class=\"running-number-cards-wrapper\">\n                                                    <div class=\"running-number-card-wrapper\">\n                                <div class=\"running-number-card-content\">\n                                    <h4 class=\"running-number-card-title\">Misure inerenti a prodotti e processi<\/h4>\n\n                                    <div class=\"running-number-card-text\">\n                                        <div class=\"numbers-part\">\n                                            <p>122 675 MWh\/a<br \/>\n16 977 t CO<sub>2<\/sub>\/a<br \/>\n12 267 535 CHF\/a<\/p>\n                                        <\/div>\n                                        <p>Questa sezione \u00e8 dedicata all\u2019analisi dei requisiti di processo, all\u2019ottimizzazione di processi e prodotti e all\u2019adeguamento dei processi. Le analisi Pinch sono uno strumento molto utile e garantiscono una maggiore sicurezza degli investimenti. Inoltre, il fatto che siano promosse dall\u2019Ufficio federale dell\u2019energia (UFE) le rende ancora pi\u00f9 interessanti.<\/p>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                                                    <div class=\"running-number-card-wrapper\">\n                                <div class=\"running-number-card-content\">\n                                    <h4 class=\"running-number-card-title\">Calore di processo<\/h4>\n\n                                    <div class=\"running-number-card-text\">\n                                        <div class=\"numbers-part\">\n                                            <p>44 857 MWh\/a<br \/>\n8327 t CO<sub>2<\/sub>\/a<br \/>\n4 485 668 CHF\/a<\/p>\n                                        <\/div>\n                                        <p>Tipiche misure in quest\u2019ambito sono ad esempio il recupero del calore, lo sfruttamento del calore residuo, la rinuncia a impianti di produzione di vapore e acqua calda, ulteriori abbassamenti del livello di temperatura, il corretto dimensionamento degli impianti di produzione, il preriscaldamento dell\u2019aria di combustione e regolazioni in base al fabbisogno. Si pu\u00f2 ricorrere anche all\u2019analisi Pinch promossa dall\u2019UFE.<\/p>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                                                    <div class=\"running-number-card-wrapper\">\n                                <div class=\"running-number-card-content\">\n                                    <h4 class=\"running-number-card-title\">Riscaldamento<\/h4>\n\n                                    <div class=\"running-number-card-text\">\n                                        <div class=\"numbers-part\">\n                                            <p>43 809 MWh\/a<br \/>\n7295 t CO<sub>2<\/sub>\/a<br \/>\n4 380 902 CHF\/a<\/p>\n                                        <\/div>\n                                        <p>In quest\u2019ambito sono previste misure quali la sostituzione delle caldaie, il recupero di calore dai fumi o altre ottimizzazioni come l\u2019abbassamento del limite di riscaldamento. In genere, le misure incentrate sulla regolazione sono realizzabili senza grandi investimenti, con semplici ottimizzazioni operative.<\/p>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n\n                    <\/section>\n    \n\n\n\n\n            <section class=\"services-block block-paddings \" id=\"services-block-6a5718c2aa601\" data-pageid=\"11715\">\n            <div class=\"posts-loader-container-bg\"><\/div>\n\n            <div class=\"container-main\">\n                <div class=\"services-title-block scrollMagic-block visibleInBackend\" data-uid=\"6a5718c2aa611\">\n                    <div class=\"services-title\">\n                        \n                                                    <h2 class=\"margin-bottom-0\">LA NOSTRA OFFERTA<\/h2>\n                                            <\/div>\n                <\/div>\n\n                <div class=\"filters-and-button-wrapper scrollMagic-block visibleInBackend\" data-uid=\"6a5718c2aa613\">\n                    \n                                    <\/div>\n\n                            <\/div>\n\n            <div class=\"services-slider scrollMagic-block visibleInBackend\" data-uid=\"6a5718c2aa615\">\n                    <a href=\"https:\/\/enaw.ch\/it\/angebot\/piano-per-la-decarbonizzazione\"  class=\"services-slider-card\" id=\"service-id-2\">\n        <div class=\"services-slider-card-inner-container\">\n            \n            <div class=\"services-slider-card-title-block\">\n                                    <div class=\"icon\" style=\"-webkit-mask: url('https:\/\/enaw.ch\/wp-content\/uploads\/2022\/05\/202211212_enaw_Icon_roadmap_outline_01cu.svg'); mask: url('https:\/\/enaw.ch\/wp-content\/uploads\/2022\/05\/202211212_enaw_Icon_roadmap_outline_01cu.svg'); mask-repeat: no-repeat; -webkit-mask-repeat: no-repeat; mask-size: contain; -webkit-mask-size: contain;\"><\/div>\n                \n                <div class=\"service-title-block\">\n                    <h3>Piano per la decarbonizzazione<\/h3>\n\n                                            <p>Con lungimiranza verso un saldo netto delle emissioni pari a zero<\/p>\n                                    <\/div>\n            <\/div>\n\n                                        <div class=\"services-slider-card-list-block\">\n                    <ul>\n                                                    <li>Ampia consulenza e pianificazione a lungo termine da un unico partner. <\/li>\n                                                    <li>Sicurezza nella pianificazione dell\u2019approvvigionamento energetico. <\/li>\n                                                    <li>Raggiungimento degli obiettivi climatici della Svizzera. <\/li>\n                                            <\/ul>\n                <\/div>\n            \n            <div class=\"btn-block\">\n                <div class=\"main-btn\">Per saperne di pi\u00f9 <\/div>\n            <\/div>\n        <\/div>\n    <\/a>\n    <a href=\"https:\/\/enaw.ch\/it\/angebot\/efficienza-delle-risorse\"  class=\"services-slider-card\" id=\"service-id-\">\n        <div class=\"services-slider-card-inner-container\">\n            \n            <div class=\"services-slider-card-title-block\">\n                                    <div class=\"icon\" style=\"-webkit-mask: url('https:\/\/enaw.ch\/wp-content\/uploads\/2022\/07\/202211212_enaw_Icon_ressourceneffizienz_outline_02cu.svg'); mask: url('https:\/\/enaw.ch\/wp-content\/uploads\/2022\/07\/202211212_enaw_Icon_ressourceneffizienz_outline_02cu.svg'); mask-repeat: no-repeat; -webkit-mask-repeat: no-repeat; mask-size: contain; -webkit-mask-size: contain;\"><\/div>\n                \n                <div class=\"service-title-block\">\n                    <h3>Efficienza delle risorse<\/h3>\n\n                                            <p>Attivit\u00e0 economica con l\u2019obiettivo di risparmiare risorse.<\/p>\n                                    <\/div>\n            <\/div>\n\n                                        <div class=\"services-slider-card-list-block\">\n                    <ul>\n                                                    <li>Scansione ambientale dell\u2019intera catena di valore<\/li>\n                                                    <li>Reporting necessari e prospettici dei dati<\/li>\n                                                    <li>Minimizzare costi, rischi e impronta ambientale in un\u2019ottica di economia circolare<\/li>\n                                            <\/ul>\n                <\/div>\n            \n            <div class=\"btn-block\">\n                <div class=\"main-btn\">Per saperne di pi\u00f9 <\/div>\n            <\/div>\n        <\/div>\n    <\/a>\n    <a href=\"https:\/\/enaw.ch\/it\/angebot\/mobilita\"  class=\"services-slider-card\" id=\"service-id-4\">\n        <div class=\"services-slider-card-inner-container\">\n            \n            <div class=\"services-slider-card-title-block\">\n                                    <div class=\"icon\" style=\"-webkit-mask: url('https:\/\/enaw.ch\/wp-content\/uploads\/2022\/07\/202211212_enaw_Icon_mobilitaet_outline_01cu.svg'); mask: url('https:\/\/enaw.ch\/wp-content\/uploads\/2022\/07\/202211212_enaw_Icon_mobilitaet_outline_01cu.svg'); mask-repeat: no-repeat; -webkit-mask-repeat: no-repeat; mask-size: contain; -webkit-mask-size: contain;\"><\/div>\n                \n                <div class=\"service-title-block\">\n                    <h3>Mobilit\u00e0<\/h3>\n\n                                            <p>Ottimizzate i veicoli, i percorsi di servizio e di trasporto nella vostra azienda<\/p>\n                                    <\/div>\n            <\/div>\n\n                                        <div class=\"services-slider-card-list-block\">\n                    <ul>\n                                                    <li>Ampia consulenza e collaborazione con partner specializzati nell\u2019attuazione. <\/li>\n                                                    <li>Realizzare ulteriori incrementi di efficienza. <\/li>\n                                                    <li>Ridurre i costi per la mobilit\u00e0 aziendale.<\/li>\n                                            <\/ul>\n                <\/div>\n            \n            <div class=\"btn-block\">\n                <div class=\"main-btn\">Per saperne di pi\u00f9 <\/div>\n            <\/div>\n        <\/div>\n    <\/a>\n    <a href=\"https:\/\/enaw.ch\/it\/angebot\/sbti\"  class=\"services-slider-card\" id=\"service-id-5\">\n        <div class=\"services-slider-card-inner-container\">\n            \n            <div class=\"services-slider-card-title-block\">\n                                    <div class=\"icon\" style=\"-webkit-mask: url('https:\/\/enaw.ch\/wp-content\/uploads\/2022\/07\/202211212_enaw_Icon_sbti_outline_01cu.svg'); mask: url('https:\/\/enaw.ch\/wp-content\/uploads\/2022\/07\/202211212_enaw_Icon_sbti_outline_01cu.svg'); mask-repeat: no-repeat; -webkit-mask-repeat: no-repeat; mask-size: contain; -webkit-mask-size: contain;\"><\/div>\n                \n                <div class=\"service-title-block\">\n                    <h3>Science Based <br>Targets Initiative (SBTi)<\/h3>\n\n                                            <p>Applicare la SBTi con il supporto dell\u2019AEnEC<\/p>\n                                    <\/div>\n            <\/div>\n\n                                        <div class=\"services-slider-card-list-block\">\n                    <ul>\n                                                    <li>Supporto individuale al momento dell\u2019iscrizione e dell\u2019acquisizione dei dati.<\/li>\n                                                    <li>Dati importanti gi\u00e0 contenuti nei tool dell\u2019AEnEC.<\/li>\n                                                    <li>Rafforzare l\u2019immagine e i vantaggi competitivi.<\/li>\n                                            <\/ul>\n                <\/div>\n            \n            <div class=\"btn-block\">\n                <div class=\"main-btn\">Per saperne di pi\u00f9 <\/div>\n            <\/div>\n        <\/div>\n    <\/a>\n    <a href=\"https:\/\/enaw.ch\/it\/angebot\/efficienza\"  class=\"services-slider-card\" id=\"service-id-6\">\n        <div class=\"services-slider-card-inner-container\">\n            \n            <div class=\"services-slider-card-title-block\">\n                                    <div class=\"icon\" style=\"-webkit-mask: url('https:\/\/enaw.ch\/wp-content\/uploads\/2022\/05\/20221212_enaw_Icon_plus_outline_01cu.svg'); mask: url('https:\/\/enaw.ch\/wp-content\/uploads\/2022\/05\/20221212_enaw_Icon_plus_outline_01cu.svg'); mask-repeat: no-repeat; -webkit-mask-repeat: no-repeat; mask-size: contain; -webkit-mask-size: contain;\"><\/div>\n                \n                <div class=\"service-title-block\">\n                    <h3>Efficienza<sup>+<\/sup><\/h3>\n\n                                            <p>Programma teso a sostenere misure supplementari di efficienza elettrica <\/p>\n                                    <\/div>\n            <\/div>\n\n                                        <div class=\"services-slider-card-list-block\">\n                    <ul>\n                                                    <li>Realizzare le misure di efficienza elettrica al limite della redditivit\u00e0.<\/li>\n                                                    <li>Ottenere gli incentivi per le misure di efficienza elettrica con un onere minimo.<\/li>\n                                                    <li>Aumentare ulteriormente l\u2019efficienza energetica in azienda.<\/li>\n                                            <\/ul>\n                <\/div>\n            \n            <div class=\"btn-block\">\n                <div class=\"main-btn\">Per saperne di pi\u00f9 <\/div>\n            <\/div>\n        <\/div>\n    <\/a>\n    <a href=\"https:\/\/enaw.ch\/it\/angebot\/programma-trasporti\"  class=\"services-slider-card\" id=\"service-id-\">\n        <div class=\"services-slider-card-inner-container\">\n            \n            <div class=\"services-slider-card-title-block\">\n                                    <div class=\"icon\" style=\"-webkit-mask: url('https:\/\/enaw.ch\/wp-content\/uploads\/2022\/07\/202211212_enaw_Icon_mobilitaet_outline_01cu.svg'); mask: url('https:\/\/enaw.ch\/wp-content\/uploads\/2022\/07\/202211212_enaw_Icon_mobilitaet_outline_01cu.svg'); mask-repeat: no-repeat; -webkit-mask-repeat: no-repeat; mask-size: contain; -webkit-mask-size: contain;\"><\/div>\n                \n                <div class=\"service-title-block\">\n                    <h3>Programma trasporti<\/h3>\n\n                                            <p>Programma di incentivazione per una maggiore efficienza dei veicoli e dei trasporti<\/p>\n                                    <\/div>\n            <\/div>\n\n                                        <div class=\"services-slider-card-list-block\">\n                    <ul>\n                                                    <li>Bonifico di 130 franchi per ogni tonnellata di CO<sub>2<\/sub> venduta.<\/li>\n                                                    <li>Coordinazione della verifica esterna del monitoraggio da parte dall\u2019AEnEC.<\/li>\n                                                    <li>Disbrigo delle pratiche amministrative con la Confederazione nell\u2019ambito dei certificati di compensazione.<\/li>\n                                            <\/ul>\n                <\/div>\n            \n            <div class=\"btn-block\">\n                <div class=\"main-btn\">Per saperne di pi\u00f9 <\/div>\n            <\/div>\n        <\/div>\n    <\/a>\n    <a href=\"https:\/\/enaw.ch\/it\/angebot\/contributi-di-incentivazione\"  class=\"services-slider-card\" id=\"service-id-\">\n        <div class=\"services-slider-card-inner-container\">\n            \n            <div class=\"services-slider-card-title-block\">\n                \n                <div class=\"service-title-block\">\n                    <h3>Contributi di incentivazione<\/h3>\n\n                                            <p>Un vantaggio per l&#8217;ambiente e il conto economico <\/p>\n                                    <\/div>\n            <\/div>\n\n                                        <div class=\"services-slider-card-list-block\">\n                    <ul>\n                                                    <li>Beneficiare di contributi di incentivazione<\/li>\n                                            <\/ul>\n                <\/div>\n            \n            <div class=\"btn-block\">\n                <div class=\"main-btn\">Per saperne di pi\u00f9 <\/div>\n            <\/div>\n        <\/div>\n    <\/a>\n    <a href=\"https:\/\/enaw.ch\/it\/angebot\/analisi-pinch\"  class=\"services-slider-card\" id=\"service-id-\">\n        <div class=\"services-slider-card-inner-container\">\n            \n            <div class=\"services-slider-card-title-block\">\n                \n                <div class=\"service-title-block\">\n                    <h3>Analisi Pinch<\/h3>\n\n                                            <p>Individuare e sfruttare il potenziale di risparmio di energia e di CO<sub>2<\/sub> nei processi complessi.<\/p>\n                                    <\/div>\n            <\/div>\n\n                        \n            <div class=\"btn-block\">\n                <div class=\"main-btn\">Per saperne di pi\u00f9 <\/div>\n            <\/div>\n        <\/div>\n    <\/a>\n            <\/div>\n\n            <div class=\"container-main\">\n                <div class=\"services-block-buttons-area\">\n                    <div class=\"slider-nav\"><\/div>\n                <\/div>\n            <\/div>\n\n                    <\/section>\n    \n\n\n\n            <section class=\"contact-block block-paddings blue-light-bg\" id=\"contact-block\">\n            <div class=\"container-main\">\n                <div class=\"contact-block-cols\">\n                    <div class=\"contact-block-text scrollMagic-block visibleInBackend\" data-uid=\"6a5718c2afa3b\">\n                                                    <p class=\"subtitle text-blue-light\">Siamo lieti di fornirvi supporto<\/p>\n                        \n                                                    <h2>Contattateci!<\/h2>\n                        \n                                                    <p class=\"desc margin-bottom-0\">La vostra azienda \u00e8 stata obbligata ad aumentare l&#8217;efficienza energetica aziendale secondo il modello dei grandi consumatori del Cantone di Vaud? Allora non esitate a contattarci. Saremo lieti di darvi una mano.<\/p>\n                        \n                                            <\/div>\n\n                    <div class=\"contact-block-form light-bg scrollMagic-block delay-1 visibleInBackend\" data-uid=\"6a5718c2afa3e\">\n                        <div class=\"frm_forms \" id=\"frm_form_38_container\" >\n<form enctype=\"multipart\/form-data\" method=\"post\" class=\"frm-show-form  frm_js_validate  frm_ajax_submit  frm_pro_form \" id=\"form_contact-form54de9d724e\" >\n<div class=\"frm_form_fields \">\n<fieldset>\n<legend class=\"frm_screen_reader\">Kontaktieren Sie uns (Startseite) (IT)<\/legend>\r\n\r\n<div class=\"frm_fields_container\">\n<input type=\"hidden\" name=\"frm_action\" value=\"create\" \/>\n<input type=\"hidden\" name=\"form_id\" value=\"38\" \/>\n<input type=\"hidden\" name=\"frm_hide_fields_38\" id=\"frm_hide_fields_38\" value=\"\" \/>\n<input type=\"hidden\" name=\"form_key\" value=\"contact-form54de9d724e\" \/>\n<input type=\"hidden\" name=\"item_meta[0]\" value=\"\" \/>\n<input type=\"hidden\" id=\"frm_submit_entry_38\" name=\"frm_submit_entry_38\" value=\"0b6c05e621\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/it\/wp-json\/wp\/v2\/pages\/11715\" \/><div id=\"frm_field_370_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container horizontal_radio\">\r\n    <div  id=\"field_anrede-1b8b5b6caa1_label\" class=\"frm_primary_label\">Titolo\r\n        <span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n    <\/div>\r\n    <div class=\"frm_opt_container\" aria-labelledby=\"field_anrede-1b8b5b6caa1_label\" role=\"radiogroup\" aria-required=\"true\">\t\t<div class=\"frm_radio\" id=\"frm_radio_370-0\">\t\t\t<label  for=\"field_anrede-1b8b5b6caa1-0\">\n\t\t\t\t\t<input type=\"radio\" name=\"item_meta[370]\" id=\"field_anrede-1b8b5b6caa1-0\" value=\"Signora\"\n\t\t data-frmval=\"Frau\" data-reqmsg=\"Il campo non deve essere vuoto.\" data-invmsg=\"Titolo non \u00e8 valido\"   \/> Signora<\/label><\/div>\n\t\t<div class=\"frm_radio\" id=\"frm_radio_370-1\">\t\t\t<label  for=\"field_anrede-1b8b5b6caa1-1\">\n\t\t\t\t\t<input type=\"radio\" name=\"item_meta[370]\" id=\"field_anrede-1b8b5b6caa1-1\" value=\"Signor\"\n\t\t data-frmval=\"Frau\" data-reqmsg=\"Il campo non deve essere vuoto.\" data-invmsg=\"Titolo non \u00e8 valido\"   \/> Signor<\/label><\/div>\n<\/div>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_371_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n    <label for=\"field_vorname-1484a63f528\" id=\"field_vorname-1484a63f528_label\" class=\"frm_primary_label\">Nome\r\n        <span class=\"frm_required\" aria-hidden=\"true\"><\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_vorname-1484a63f528\" name=\"item_meta[371]\" value=\"\"  placeholder=\"Nome *\" data-reqmsg=\"Il campo non deve essere vuoto.\" aria-required=\"true\" data-invmsg=\"Name is invalid\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_372_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n    <label for=\"field_nachname-1d045581fa3\" id=\"field_nachname-1d045581fa3_label\" class=\"frm_primary_label\">Cognome\r\n        <span class=\"frm_required\" aria-hidden=\"true\"><\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_nachname-1d045581fa3\" name=\"item_meta[372]\" value=\"\"  placeholder=\"Cognome *\" data-reqmsg=\"Il campo non deve essere vuoto.\" aria-required=\"true\" data-invmsg=\"Name is invalid\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_373_container\" class=\"frm_form_field form-field  frm_top_container\">\r\n    <label for=\"field_unternehmen-1fa15bacf6b\" id=\"field_unternehmen-1fa15bacf6b_label\" class=\"frm_primary_label\">Azienda\r\n        <span class=\"frm_required\" aria-hidden=\"true\"><\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_unternehmen-1fa15bacf6b\" name=\"item_meta[373]\" value=\"\"  placeholder=\"Azienda\" data-invmsg=\"Text is invalid\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_374_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n    <label for=\"field_email-17c63992373\" id=\"field_email-17c63992373_label\" class=\"frm_primary_label\">E-mail\r\n        <span class=\"frm_required\" aria-hidden=\"true\"><\/span>\r\n    <\/label>\r\n    <input type=\"email\" id=\"field_email-17c63992373\" name=\"item_meta[374]\" value=\"\"  placeholder=\"E-mail *\" data-reqmsg=\"Il campo non deve essere vuoto.\" aria-required=\"true\" data-invmsg=\"Inserire un indirizzo e-mail valido.\" aria-invalid=\"false\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_375_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n    <label for=\"field_telefonnummer-1566c7a3fcb\" id=\"field_telefonnummer-1566c7a3fcb_label\" class=\"frm_primary_label\">Numero di telefono\r\n        <span class=\"frm_required\" aria-hidden=\"true\"><\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_telefonnummer-1566c7a3fcb\" name=\"item_meta[375]\" value=\"\"  placeholder=\"Numero di telefono *\" data-reqmsg=\"Il campo non deve essere vuoto.\" aria-required=\"true\" data-invmsg=\"Text is invalid\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_376_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n    <label for=\"field_message_1964ee9eb45\" id=\"field_message_1964ee9eb45_label\" class=\"frm_primary_label\">Il vostro messaggio* \r\n        <span class=\"frm_required\" aria-hidden=\"true\"><\/span>\r\n    <\/label>\r\n    <textarea name=\"item_meta[376]\" id=\"field_message_1964ee9eb45\" rows=\"5\"  placeholder=\"Il vostro messaggio*\" data-reqmsg=\"Il campo non deve essere vuoto.\" aria-required=\"true\" data-invmsg=\"Il vostro messaggio*  non \u00e8 valido\" aria-invalid=\"false\"  ><\/textarea>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_377_container\" class=\"frm_form_field  frm_html_container form-field\">\n<h4>Come possiamo contattarvi?<\/h4>\n<\/div>\n<div id=\"frm_field_378_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container horizontal_radio\">\r\n    <div  id=\"field_kontaktieren_typ-1335b0acb28_label\" class=\"frm_primary_label\">Come possiamo contattarvi?*\r\n        <span class=\"frm_required\" aria-hidden=\"true\"><\/span>\r\n    <\/div>\r\n    <div class=\"frm_opt_container\" aria-labelledby=\"field_kontaktieren_typ-1335b0acb28_label\" role=\"radiogroup\" aria-required=\"true\">\t\t<div class=\"frm_radio\" id=\"frm_radio_378-0\">\t\t\t<label  for=\"field_kontaktieren_typ-1335b0acb28-0\">\n\t\t\t\t\t<input type=\"radio\" name=\"item_meta[378]\" id=\"field_kontaktieren_typ-1335b0acb28-0\" value=\"Via e-mail\"\n\t\t data-frmval=\"Per E-Mail\" data-reqmsg=\"Il campo non deve essere vuoto.\" data-invmsg=\"Come possiamo contattarvi?* non \u00e8 valido\"   \/> Via e-mail<\/label><\/div>\n\t\t<div class=\"frm_radio\" id=\"frm_radio_378-1\">\t\t\t<label  for=\"field_kontaktieren_typ-1335b0acb28-1\">\n\t\t\t\t\t<input type=\"radio\" name=\"item_meta[378]\" id=\"field_kontaktieren_typ-1335b0acb28-1\" value=\"Per telefono\"\n\t\t data-frmval=\"Per E-Mail\" data-reqmsg=\"Il campo non deve essere vuoto.\" data-invmsg=\"Come possiamo contattarvi?* non \u00e8 valido\"   \/> Per telefono<\/label><\/div>\n<\/div>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_379_container\" class=\"frm_form_field form-field  frm_top_container hidden_field\">\r\n    <label for=\"field_formlang-1614d7a3e1a\" id=\"field_formlang-1614d7a3e1a_label\" class=\"frm_primary_label\">Language\r\n        <span class=\"frm_required\" aria-hidden=\"true\"><\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_formlang-1614d7a3e1a\" name=\"item_meta[379]\" value=\"it\"  data-frmval=\"it\" data-invmsg=\"Text is invalid\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_523_container\" class=\"frm_form_field form-field  frm_none_container\">\r\n    <label for=\"g-recaptcha-response\" id=\"field_f2iix_label\" class=\"frm_primary_label\">reCAPTCHA\r\n        <span class=\"frm_required\" aria-hidden=\"true\"><\/span>\r\n    <\/label>\r\n    <div  id=\"field_f2iix\" class=\"frm-g-recaptcha\" data-sitekey=\"6LcWiwMkAAAAAB9xaAtRZBFAoDz1lFDpcqFx3g88\" data-size=\"invisible\" data-theme=\"light\"><\/div>\r\n    \r\n    \r\n<\/div>\n\t<input type=\"hidden\" name=\"item_key\" value=\"\" \/>\n\t\t\t<div id=\"frm_field_1410_container\">\n\t\t\t<label for=\"field_3jm6t\" >\n\t\t\t\tSe sei un essere umano, lascia questo campo vuoto.\t\t\t<\/label>\n\t\t\t<input  id=\"field_3jm6t\" type=\"text\" class=\"frm_form_field form-field frm_verify\" name=\"item_meta[1410]\" value=\"\"  \/>\n\t\t<\/div>\n\t\t<input name=\"frm_state\" type=\"hidden\" value=\"yDn8HWQ2IVPy0V+LZYRcIXmMpx566n8L3M6TU4od3ZQGT\/A\/Dj3wLF483TlsFBW1\" \/><div class=\"frm_submit\">\r\n\r\n<button class=\"frm_button_submit frm_final_submit\" type=\"submit\"   formnovalidate=\"formnovalidate\">Senden<\/button>\r\n\r\n<\/div><\/div>\n<\/fieldset>\n<\/div>\n\n<\/form>\n<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n\n                    <\/section>\n    \n\n\n\n\n    <section class=\"title-text-button-block  title-text-button-block-6a5718c2b33ef block-paddings \" id=\"\">\n        <div class=\"container-main\">\n                                        <div class=\"title-block title-block-6a5718c2b3436 scrollMagic-block visibleInBackend\" data-uid=\"6a5718c2b3437\">\n                    <p class=\"subtitle text-blue-light\">Vai ad altri cantoni<\/p>\n        \n                    <h2>Impatto delle aziende nei cantoni<\/h2>\n            <\/div>\n\n            <div class=\"narrow-container\">\n                                    <div class=\"description-block scrollMagic-block visibleInBackend\" data-uid=\"6a5718c2b343b\">\n                        <p>Vi interessa conoscere l\u2019impatto cumulativo delle aziende del vostro cantone? Nelle schede informative cantonali troverete gli indicatori aggiornati della vostra regione.<\/p>\n                    <\/div>\n                \n                \n                                    <div class=\"links-items\">\n                                                    <a href=\"https:\/\/enaw.ch\/it\/protezione-del-clima-ed-efficienza-energetica-nel-cantone-di-argovia\/\" class=\"main-btn\" target=\"_blank\" >Cantone di Argovia<\/a>\n                                                    <a href=\"https:\/\/enaw.ch\/it\/protezione-del-clima-ed-efficienza-energetica-nel-cantone-di-berna\/\" class=\"main-btn\" target=\"_blank\" >Cantone di Berna<\/a>\n                                                    <a href=\"https:\/\/enaw.ch\/it\/protezione-del-clima-ed-efficienza-energetica-nel-cantone-dei-grigioni\/\" class=\"main-btn\" target=\"_blank\" >Cantone dei Grigioni<\/a>\n                                                    <a href=\"https:\/\/enaw.ch\/it\/protezione-del-clima-ed-efficienza-energetica-nel-cantone-di-neuchatel\/\" class=\"main-btn\" target=\"_blank\" >Cantone di Neuch\u00e2tel<\/a>\n                                                    <a href=\"https:\/\/enaw.ch\/it\/protezione-del-clima-ed-efficienza-energetica-nel-cantone-di-san-gallo\/\" class=\"main-btn\" target=\"_blank\" >Cantone di San Gallo<\/a>\n                                                    <a href=\"https:\/\/enaw.ch\/it\/protezione-del-clima-ed-efficienza-energetica-nel-cantone-di-soletta\/\" class=\"main-btn\" target=\"_blank\" >Cantone di Soletta<\/a>\n                                                    <a href=\"https:\/\/enaw.ch\/it\/protezione-del-clima-ed-efficienza-energetica-nel-cantone-di-neuchatel\/\" class=\"main-btn\" target=\"_blank\" >Cantone Ticino<\/a>\n                                                    <a href=\"https:\/\/enaw.ch\/it\/protezione-del-clima-ed-efficienza-energetica-nel-cantone-di-zurigo\/\" class=\"main-btn\" target=\"_blank\" >Cantone di Zurigo<\/a>\n                                            <\/div>\n                            <\/div>\n        <\/div>\n\n            <\/section>\n\n    \n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":10821,"parent":0,"menu_order":5,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-11715","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Protezione del clima ed efficienza energetica nel Cantone di Vaud | Agenzia dell\u2019energia per l\u2019economia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/enaw.ch\/it\/protezione-del-clima-ed-efficienza-energetica-nel-cantone-di-vaud\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Protezione del clima ed efficienza energetica nel Cantone di Vaud\" \/>\n<meta property=\"og:url\" content=\"https:\/\/enaw.ch\/it\/protezione-del-clima-ed-efficienza-energetica-nel-cantone-di-vaud\" \/>\n<meta property=\"og:site_name\" content=\"Agenzia dell\u2019energia per l\u2019economia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/enaw.aenec\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-19T12:36:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/enaw.ch\/wp-content\/uploads\/2022\/12\/enaw_waadt_header-600x133.jpg\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@info_enaw\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/enaw.ch\\\/it\\\/protezione-del-clima-ed-efficienza-energetica-nel-cantone-di-vaud\",\"url\":\"https:\\\/\\\/enaw.ch\\\/it\\\/protezione-del-clima-ed-efficienza-energetica-nel-cantone-di-vaud\",\"name\":\"Protezione del clima ed efficienza energetica nel Cantone di Vaud | Agenzia dell\u2019energia per l\u2019economia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/enaw.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/enaw.ch\\\/it\\\/protezione-del-clima-ed-efficienza-energetica-nel-cantone-di-vaud#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/enaw.ch\\\/it\\\/protezione-del-clima-ed-efficienza-energetica-nel-cantone-di-vaud#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/enaw.ch\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/enaw_waadt_header.jpg\",\"datePublished\":\"2022-08-24T09:51:19+00:00\",\"dateModified\":\"2024-07-19T12:36:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/enaw.ch\\\/it\\\/protezione-del-clima-ed-efficienza-energetica-nel-cantone-di-vaud#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/enaw.ch\\\/it\\\/protezione-del-clima-ed-efficienza-energetica-nel-cantone-di-vaud\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/enaw.ch\\\/it\\\/protezione-del-clima-ed-efficienza-energetica-nel-cantone-di-vaud#primaryimage\",\"url\":\"https:\\\/\\\/enaw.ch\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/enaw_waadt_header.jpg\",\"contentUrl\":\"https:\\\/\\\/enaw.ch\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/enaw_waadt_header.jpg\",\"width\":1800,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/enaw.ch\\\/it\\\/protezione-del-clima-ed-efficienza-energetica-nel-cantone-di-vaud#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/enaw.ch\\\/it\\\/beispiel-seite\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Protezione del clima ed efficienza energetica nel Cantone di Vaud\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/enaw.ch\\\/#website\",\"url\":\"https:\\\/\\\/enaw.ch\\\/\",\"name\":\"Energie-Agentur der Wirtschaft\",\"description\":\"Un altro sito web WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/enaw.ch\\\/#organization\"},\"alternateName\":\"EnAW\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/enaw.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/enaw.ch\\\/#organization\",\"name\":\"EnAW Energie-Agentur der Wirtschaft\",\"alternateName\":\"EnAW\",\"url\":\"https:\\\/\\\/enaw.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/enaw.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/enaw.ch\\\/wp-content\\\/uploads\\\/Logos\\\/EnAW_Logo_DE_RGB_black-1.svg\",\"contentUrl\":\"https:\\\/\\\/enaw.ch\\\/wp-content\\\/uploads\\\/Logos\\\/EnAW_Logo_DE_RGB_black-1.svg\",\"width\":219,\"height\":38,\"caption\":\"EnAW Energie-Agentur der Wirtschaft\"},\"image\":{\"@id\":\"https:\\\/\\\/enaw.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/enaw.aenec\",\"https:\\\/\\\/x.com\\\/info_enaw\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/enaw\\\/\"],\"description\":\"Seit 2001 setzen wir gemeinsam mit den Unternehmen auf wirtschaftlichen Klimaschutz. Wir bieten individuelle L\u00f6sungen, um die Energie- und Ressourceneffizienz kontinuierlich zu steigern. Unsere 126 EnAW-Beraterinnen und EnAW-Berater kennen sich in allen Branchen und Wirtschaftszweigen aus und begleiten auch Ihr Unternehmen kompetent auf dem Weg zu weniger CO2, tieferen Kosten und mehr Energie- und Ressourceneffizienz.\",\"email\":\"news@enaw.ch\",\"telephone\":\"+41 44 388 24 24\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Protezione del clima ed efficienza energetica nel Cantone di Vaud | Agenzia dell\u2019energia per l\u2019economia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/enaw.ch\/it\/protezione-del-clima-ed-efficienza-energetica-nel-cantone-di-vaud","og_locale":"it_IT","og_type":"article","og_title":"Protezione del clima ed efficienza energetica nel Cantone di Vaud","og_url":"https:\/\/enaw.ch\/it\/protezione-del-clima-ed-efficienza-energetica-nel-cantone-di-vaud","og_site_name":"Agenzia dell\u2019energia per l\u2019economia","article_publisher":"https:\/\/www.facebook.com\/enaw.aenec","article_modified_time":"2024-07-19T12:36:14+00:00","og_image":[{"url":"https:\/\/enaw.ch\/wp-content\/uploads\/2022\/12\/enaw_waadt_header-600x133.jpg","type":"image\/png","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@info_enaw","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/enaw.ch\/it\/protezione-del-clima-ed-efficienza-energetica-nel-cantone-di-vaud","url":"https:\/\/enaw.ch\/it\/protezione-del-clima-ed-efficienza-energetica-nel-cantone-di-vaud","name":"Protezione del clima ed efficienza energetica nel Cantone di Vaud | Agenzia dell\u2019energia per l\u2019economia","isPartOf":{"@id":"https:\/\/enaw.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/enaw.ch\/it\/protezione-del-clima-ed-efficienza-energetica-nel-cantone-di-vaud#primaryimage"},"image":{"@id":"https:\/\/enaw.ch\/it\/protezione-del-clima-ed-efficienza-energetica-nel-cantone-di-vaud#primaryimage"},"thumbnailUrl":"https:\/\/enaw.ch\/wp-content\/uploads\/2022\/12\/enaw_waadt_header.jpg","datePublished":"2022-08-24T09:51:19+00:00","dateModified":"2024-07-19T12:36:14+00:00","breadcrumb":{"@id":"https:\/\/enaw.ch\/it\/protezione-del-clima-ed-efficienza-energetica-nel-cantone-di-vaud#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/enaw.ch\/it\/protezione-del-clima-ed-efficienza-energetica-nel-cantone-di-vaud"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/enaw.ch\/it\/protezione-del-clima-ed-efficienza-energetica-nel-cantone-di-vaud#primaryimage","url":"https:\/\/enaw.ch\/wp-content\/uploads\/2022\/12\/enaw_waadt_header.jpg","contentUrl":"https:\/\/enaw.ch\/wp-content\/uploads\/2022\/12\/enaw_waadt_header.jpg","width":1800,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/enaw.ch\/it\/protezione-del-clima-ed-efficienza-energetica-nel-cantone-di-vaud#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/enaw.ch\/it\/beispiel-seite"},{"@type":"ListItem","position":2,"name":"Protezione del clima ed efficienza energetica nel Cantone di Vaud"}]},{"@type":"WebSite","@id":"https:\/\/enaw.ch\/#website","url":"https:\/\/enaw.ch\/","name":"Energie-Agentur der Wirtschaft","description":"Un altro sito web WordPress","publisher":{"@id":"https:\/\/enaw.ch\/#organization"},"alternateName":"EnAW","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/enaw.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/enaw.ch\/#organization","name":"EnAW Energie-Agentur der Wirtschaft","alternateName":"EnAW","url":"https:\/\/enaw.ch\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/enaw.ch\/#\/schema\/logo\/image\/","url":"https:\/\/enaw.ch\/wp-content\/uploads\/Logos\/EnAW_Logo_DE_RGB_black-1.svg","contentUrl":"https:\/\/enaw.ch\/wp-content\/uploads\/Logos\/EnAW_Logo_DE_RGB_black-1.svg","width":219,"height":38,"caption":"EnAW Energie-Agentur der Wirtschaft"},"image":{"@id":"https:\/\/enaw.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/enaw.aenec","https:\/\/x.com\/info_enaw","https:\/\/www.linkedin.com\/company\/enaw\/"],"description":"Seit 2001 setzen wir gemeinsam mit den Unternehmen auf wirtschaftlichen Klimaschutz. Wir bieten individuelle L\u00f6sungen, um die Energie- und Ressourceneffizienz kontinuierlich zu steigern. Unsere 126 EnAW-Beraterinnen und EnAW-Berater kennen sich in allen Branchen und Wirtschaftszweigen aus und begleiten auch Ihr Unternehmen kompetent auf dem Weg zu weniger CO2, tieferen Kosten und mehr Energie- und Ressourceneffizienz.","email":"news@enaw.ch","telephone":"+41 44 388 24 24"}]}},"_links":{"self":[{"href":"https:\/\/enaw.ch\/it\/wp-json\/wp\/v2\/pages\/11715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enaw.ch\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/enaw.ch\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/enaw.ch\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/enaw.ch\/it\/wp-json\/wp\/v2\/comments?post=11715"}],"version-history":[{"count":2,"href":"https:\/\/enaw.ch\/it\/wp-json\/wp\/v2\/pages\/11715\/revisions"}],"predecessor-version":[{"id":24345,"href":"https:\/\/enaw.ch\/it\/wp-json\/wp\/v2\/pages\/11715\/revisions\/24345"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/enaw.ch\/it\/wp-json\/wp\/v2\/media\/10821"}],"wp:attachment":[{"href":"https:\/\/enaw.ch\/it\/wp-json\/wp\/v2\/media?parent=11715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}