{"id":7343,"date":"2020-02-25T22:20:00","date_gmt":"2020-02-25T21:20:00","guid":{"rendered":"https:\/\/enaw.ch\/so-suess-schmeckt-nachhaltige-lokale-energie\/"},"modified":"2023-06-08T17:12:33","modified_gmt":"2023-06-08T15:12:33","slug":"le-gout-de-lenergie-locale-durable","status":"publish","type":"post","link":"https:\/\/enaw.ch\/fr\/le-gout-de-lenergie-locale-durable","title":{"rendered":"LE GO\u00dbT DE L\u2019\u00c9NERGIE LOCALE, DURABLE"},"content":{"rendered":"\n<div class=\"wp-block-columns is-style-block-with-sidebar is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"is-style-lead-paragraph wp-block-paragraph\">Recours au bois local via un chauffage \u00e0 distance, consommation de mazout divis\u00e9e par quatre, 10 % d\u00e9j\u00e0 de l\u2019\u00e9lectricit\u00e9 d\u2019origine solaire, le reste certifi\u00e9 hydraulique, froid pr\u00e9lev\u00e9 dans l\u2019environnement : \u00ab durable \u00bb prend plus d\u2019un sens chez Camille Bloch SA, dont les sp\u00e9cialit\u00e9s chocolati\u00e8res sont un succ\u00e8s jamais d\u00e9menti depuis les ann\u00e9es 1940.<\/p>\n\n\n\n            <section class=\"container-media-slider-block block-paddings  \">\n            <div class=\"container-main\">\n                <div class=\"container-media-slider-content\">\n                    <div class=\"container-media-slider js-main-slider scrollMagic-block visibleInBackend\" data-uid=\"6a574e5dad2b8\" data-nav=\"#container-media-slider-nav-6a574e5dad2b8\" id=\"container-media-slider-6a574e5dad2b8\">\n                                                    \n                            <div class=\"item-block\">\n                                                                                                                                                                \n                                \n                                                                                                            <div class=\"simple-image desk  \" style=\"background-image: url(https:\/\/enaw.ch\/wp-content\/uploads\/Aktuell\/camille_bloch_web_1068x565.jpg)\"><\/div>\n\n                                        <div class=\"simple-image mob  \" style=\"background-image: url(https:\/\/enaw.ch\/wp-content\/uploads\/Aktuell\/camille_bloch_web_1068x565.jpg)\"><\/div>\n                                                                    \n                                                            <\/div>\n                                            <\/div>\n\n                    <div class=\"container-media-slider-nav js-nav-slider\" data-main=\"#container-media-slider-6a574e5dad2b8\" id=\"container-media-slider-nav-6a574e5dad2b8\">\n                                                                                    <div class=\"item-block\">\n                                    <p class=\"small margin-bottom-0\">Entre l\u2019isolation des premiers b\u00e2timents de Camille Bloch, \u00e0 droite, et les exigences appliqu\u00e9es \u00e0 ceux inaugur\u00e9s en 2017, l\u2019ensemble du site r\u00e9pond d\u00e9sormais quasiment aux normes Minergie.<\/p>\n                                <\/div>\n                                                                        <\/div>\n\n                                    <\/div>\n            <\/div>\n        <\/section>\n    \n\n\n\n<p class=\"wp-block-paragraph\">Fond\u00e9e en 1929 \u00e0 Berne, la chocolaterie Camille Bloch SA s\u2019est d\u00e9plac\u00e9e en 1935 \u00e0 Courtelary, dans le Jura bernois, dans une ancienne fabrique de papier proche d\u2019une petite rivi\u00e8re, la Suze. Elle y emploie aujourd\u2019hui pr\u00e8s de 200 personnes. Cinqui\u00e8me en taille des fabricants suisses de chocolat, Camille Bloch produit environ 3 500 t de chocolat par an : le fameux Ragusa, n\u00e9 en 1942, la gamme Torino initi\u00e9e en 1948 et des chocolats fourr\u00e9s \u00e0 la liqueur. 20 % de cette production sont export\u00e9s. En Suisse, la part de march\u00e9 a doubl\u00e9 en moins de dix ans, passant les 5 %. Successions familiales, agrandissements et transformations ont rythm\u00e9 le progr\u00e8s r\u00e9gulier de l\u2019entreprise. De r\u00e9cents am\u00e9nagements permettront \u00e0 terme un doublement de la production. Inaugur\u00e9e en octobre 2017, l\u2019extension incluant un superbe espace d\u2019accueil pour les visiteurs illustre pleinement une volont\u00e9 aboutie d\u2019efficacit\u00e9 \u00e9nerg\u00e9tique. \u00ab Entr\u00e9e \u00e0 l\u2019AEnEC en 2014, Camille Bloch SA est un participant ouvert \u00e0 l\u2019innovation et au changement, qui agit avec ambition et rapidit\u00e9 \u00bb, appr\u00e9cie le conseiller AEnEC Fabrice Marchal.<\/p>\n\n\n\n                    <div id=\"r6a574e5dad606\" class=\"default-single-post-title show-in-sidebar-menu\">\n                <h4>MA\u00ceTRISE DU CHAUD, DU FROID \u2026<\/h4>\n            <\/div>\n        \n\n\n\n<p class=\"wp-block-paragraph\">Un chocolatier soigne l\u2019emballage de ses produits, Camille Bloch a soign\u00e9 aussi celui de ses installations. \u00ab Entre l\u2019isolation de b\u00e2timents h\u00e9rit\u00e9s d\u2019un temps o\u00f9 \u00e9conomiser l\u2019\u00e9nergie n\u2019\u00e9tait pas une priorit\u00e9, et les hautes exigences appliqu\u00e9es aux b\u00e2timents neufs, l\u2019ensemble du site est quasi aux normes Minergie \u00bb, souligne Jean Kernen, le directeur industriel. \u00c0 l\u2019int\u00e9rieur, au long des cha\u00eenes de production, c\u2019est avec une m\u00eame efficacit\u00e9 qu\u2019on souffle le chaud et le froid requis pour la fabrication de sp\u00e9cialit\u00e9s chocolati\u00e8res. Les f\u00e8ves de cacao ou noisettes appel\u00e9es \u00e0 se muer en p\u00e2te sont torr\u00e9fi\u00e9es puis moulues pour engendrer une masse liquide. Celle-ci est additionn\u00e9e d\u2019ingr\u00e9dients secs \u2013 sucre, poudre de lait \u2013 et p\u00e9trie. La p\u00e2te obtenue, granuleuse, est encore broy\u00e9e, affin\u00e9e. Intervient alors le m\u00e9lange avec le beurre de cacao, pr\u00e9parant au \u00ab conchage \u00bb, un brassage intensif \u00e0 60 \u00b0C pendant 12 \u00e0 24 heures, par tranches de 3 \u00e0 6 t. S\u2019ensuit le temp\u00e9rage, avec un premier refroidissement \u00e0 45 \u00b0C pour le stockage puis un second \u00e0 27 \u00e0 30 \u00b0C lorsque le chocolat est coul\u00e9 dans les moules aux formes qui nous sont famili\u00e8res.<\/p>\n\n\n\n                    <div id=\"r6a574e5dad72b\" class=\"default-single-post-title show-in-sidebar-menu\">\n                <h4>UNE CONVERGENCE EXEMPLAIRE<\/h4>\n            <\/div>\n        \n\n\n\n<p class=\"wp-block-paragraph\">\u00ab L\u2019essentiel de notre chaleur provient depuis 2016 d\u2019un chauffage \u00e0 distance au bois. Celui-ci est n\u00e9 en 2015 de la volont\u00e9 d\u2019un entrepreneur de Courtelary de r\u00e9pondre avec du bois de la r\u00e9gion aux besoins de chaleur tant des particuliers que de la commune et des institutions et entreprises int\u00e9ress\u00e9es \u00bb, relate Jean Kernen. Camille Bloch est d\u00e9sormais approvisionn\u00e9 en \u00e9nergie renouvelable, et \u00ab La Praye Energie SA \u00bb s\u2019est attach\u00e9 un gros consommateur de chaleur en toute saison, ce qui participe \u00e0 la viabilit\u00e9 de son projet. De plus, une conversation fortuite de l\u2019entrepreneur avec le directeur d\u2019une cimenterie voisine, elle aussi participante AEnEC, a men\u00e9 \u00e0 ce que les cendres, plut\u00f4t qu\u2019\u00eatre stock\u00e9es inutilement \u2013 et co\u00fbteusement \u2013 en d\u00e9charge, entrent d\u00e9sormais dans la composition de ciments, ce qui r\u00e9duit la quantit\u00e9 de calcaire br\u00fbl\u00e9e pour leur production, et donc les \u00e9missions de&nbsp;CO<sub>2<\/sub>&nbsp;inh\u00e9rentes. S\u2019agissant de bilan carbone, celui de Camille Bloch a fort \u00e9volu\u00e9. \u00ab Le recours au bois local a fait passer notre consommation de mazout de 230&nbsp;000 \u00e0 57&nbsp;000 l annuellement \u2013 la chaudi\u00e8re \u00e0 mazout reste en place pour le secours et l\u2019appoint \u00bb, pr\u00e9cise Jean-Philippe Simon, responsable Infrastructures. La chaudi\u00e8re \u00e0 copeaux assure le chauffage des locaux et de quasi tous les syst\u00e8mes impliqu\u00e9s dans la production de chocolat : conduites \u00e0 double manteau dans lesquels celui-ci circule, cuves de travail et de stockage \u2013 seuls quelques corps de chauffe pour des fonctions sp\u00e9cifiques utilisent l\u2019\u00e9lectricit\u00e9. Autre source renouvelable, le photovolta\u00efque d\u00e9ploy\u00e9 sur le toit apporte 350&nbsp;000 kWh annuellement. L\u2019installation a \u00e9t\u00e9 stimul\u00e9e par un progr\u00e8s de la loi, \u00ab sans la possibilit\u00e9 d\u2019autoconsommation, nous ne l\u2019aurions pas int\u00e9gr\u00e9e \u00bb, remarque Jean Kernen. Le solaire assure d\u00e9sormais 10 % des besoins \u00e9lectriques. Le reste des 3 GWh que n\u00e9cessite annuellement la fabrique sont renouvelables \u00e9galement, certifi\u00e9s d\u2019origine hydraulique.<\/p>\n\n\n\n                    <div id=\"r6a574e5dad815\" class=\"default-single-post-title show-in-sidebar-menu\">\n                <h4>RENOUVELABLE ET \u00c9CONOMIES<\/h4>\n            <\/div>\n        \n\n\n\n<p class=\"wp-block-paragraph\">La part d\u2019\u00e9lectricit\u00e9 pour le brassage du chocolat s\u2019est r\u00e9duite de mani\u00e8re spectaculaire quand un \u00ab h\u00e9ritage \u00bb du pass\u00e9, 11 moteurs \u00e0 vis sans fin de 2 kW qui n\u00e9cessitaient de fonctionner en permanence ont \u00e9t\u00e9 remplac\u00e9s par un moteur de 0,55 kW avec r\u00e9ducteur \u00e0 engrenages qui ne tourne que 5 \u00e0 10 minutes par heure. \u00ab M\u00eame r\u00e9sultat mais avec une \u00e9conomie d\u2019\u00e9lectricit\u00e9 de 94 %. \u00bb, se&nbsp;f\u00e9licite Jean-Philippe Simon, soulignant des \u00e9conomies \u00e9galement pour le circuit d\u2019air comprim\u00e9, gr\u00e2ce \u00e0 de nouveaux \u00e9quipements, redimensionn\u00e9s, et des temps d\u2019usage judicieux. Quant \u00e0 l\u2019autre versant des exigences thermiques, le froid, \u00ab il est aussi en partie d\u2019origine hydraulique. Le pompage conc\u00e9d\u00e9 de 115&nbsp;000 m3&nbsp;par an d\u2019eau de la Suze voisine livre l\u2019\u00e9quivalent de 800&nbsp;000 kWh thermiques. Et depuis 2013, du froid provient aussi d\u2019une installation de free cooling ainsi que de pompes \u00e0 chaleur int\u00e9gr\u00e9es \u00e0 certaines machines. \u00bb La chaleur r\u00e9cup\u00e9r\u00e9e sert au chauffage de l\u2019eau sanitaire tout comme celle gagn\u00e9e en cours de production sous forme de vapeur condens\u00e9e, et celle capt\u00e9e sur les compresseurs du circuit de froid. \u00ab Nos efforts portent autant sur la r\u00e9duction de notre consommation que sur l\u2019utilisation de sources d\u2019\u00e9nergie renouvelables \u00bb, r\u00e9sume Jean Kernen. \u00ab Nous faisons tout ce qu\u2019il est raisonnablement possible de faire et sommes pr\u00eats \u00e0 investir un peu plus pour mettre en oeuvre des solutions durables. \u00bb<\/p>\n\n\n\n            <section class=\"infos-block block-paddings  \">\n            <div class=\"container-main\">\n\n                                                    <div class=\"title-block title-block-6a574e5daddac scrollMagic-block visibleInBackend\" data-uid=\"6a574e5daddae\">\n        \n                    <h2>Informations<\/h2>\n            <\/div>\n\n                \n                <div class=\"narrow-container\">\n                    <div class=\"infos\">\n\n                                                    <div class=\"info-block info-block-6a574e5daddb1  scrollMagic-block visibleInBackend\" data-uid=\"6a574e5daddb2\">\n\n                                \n                                                                    <div class=\" info-items\">\n                                            <div class=\" info-item\">\n        <svg width=\"40\" height=\"42\" viewBox=\"0 0 40 42\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n            <path d=\"M20.0034 2.25146V27.2515\" stroke=\"#99ABF2\" stroke-width=\"4\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n            <path d=\"M12.5034 19.7515L20.0034 27.2515L27.5034 19.7515\" stroke=\"#99ABF2\" stroke-width=\"4\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n            <path d=\"M26.2533 8.5H30C31.3261 8.5 32.5979 9.02678 33.5355 9.96447C34.4732 10.9021 35 12.1739 35 13.5V34.75C35 36.0761 34.4732 37.3479 33.5355 38.2855C32.5979 39.2232 31.3261 39.75 30 39.75H10C8.67392 39.75 7.40215 39.2232 6.46447 38.2855C5.52678 37.3479 5 36.0761 5 34.75V13.5C5 12.1739 5.52678 10.9021 6.46447 9.96447C7.40215 9.02678 8.67392 8.5 10 8.5H13.75\" stroke=\"#99ABF2\" stroke-width=\"4\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n        <\/svg>\n        <a href=\"https:\/\/enaw.ch\/wp-content\/uploads\/2020\/02\/enaw_konkret_camillebloch_f_web.pdf\" target=\"_blank\" class=\"heading-h4 margin-bottom-0\">Actifs Camille Bloch SA : le go\u00fbt de l&rsquo;\u00e9nergie locale, durable (PDF)<\/a>\n    <\/div>\n    <div class=\" info-item\">\n        <svg width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n            <path d=\"M20.7151 29.2916L14.2826 35.724V35.724C11.9135 38.0919 8.0737 38.0919 5.70458 35.724L4.27566 34.2951V34.2951C1.90811 31.927 1.90811 28.0882 4.27566 25.7201L13.5674 16.4268V16.4268C15.9366 14.0589 19.7764 14.0589 22.1455 16.4268L23.5744 17.8572\" stroke=\"#99ABF2\" stroke-width=\"4\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n            <path d=\"M19.2846 10.7081L25.7171 4.27718V4.27718C28.0847 1.90842 31.9243 1.90749 34.2931 4.27511C34.2938 4.2758 34.2944 4.27649 34.2951 4.27718L35.7241 5.70457V5.70457C38.0916 8.07267 38.0916 11.9115 35.7241 14.2796L26.4323 23.5729V23.5729C24.0647 25.9417 20.225 25.9426 17.8563 23.575C17.8556 23.5743 17.8549 23.5736 17.8542 23.5729L16.4253 22.1425\" stroke=\"#99ABF2\" stroke-width=\"4\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n        <\/svg>\n        <a href=\"https:\/\/camillebloch.swiss\/fr\/\" target=\"_blank\" class=\"heading-h4 margin-bottom-0\">Camille Bloche SA<\/a>\n    <\/div>\n                                    <\/div>\n                                \n                                \n                                \n                                                            <\/div>\n                        \n                    <\/div>\n                <\/div>\n            <\/div>\n\n                    <\/section>\n    \n\n\n\n    <section class=\"share-links-block share-links-block-section scrollMagic-block visibleInBackend\" data-uid=\"6a574e5dadedf\">\n        <div class=\"container-main\">\n                        \n<div class=\"share-links\">\n    <a href=\"http:\/\/www.linkedin.com\/shareArticle?mini=true&amp;url=https:\/\/enaw.ch\/fr\/le-gout-de-lenergie-locale-durable&amp;title=LE GO\u00dbT DE L\u2019\u00c9NERGIE LOCALE, DURABLE&amp;summary=Recours au bois local via un chauffage \u00e0 distance, consommation de mazout divis\u00e9e par quatre, 10 % d\u00e9j\u00e0 de l\u2019\u00e9lectricit\u00e9 d\u2019origine solaire, le reste certifi\u00e9 hydraulique, froid pr\u00e9lev\u00e9 dans l\u2019environnement : \u00ab durable \u00bb prend plus d\u2019un sens chez Camille Bloch SA, dont les sp\u00e9cialit\u00e9s chocolati\u00e8res sont un succ\u00e8s jamais d\u00e9menti depuis les ann\u00e9es 1940.\" target=\"_blank\"><span><i class=\"fab fa-linkedin-in\"><\/i><\/span><\/a>\n    <a href=\"https:\/\/twitter.com\/intent\/tweet?text=LE GO\u00dbT DE L\u2019\u00c9NERGIE LOCALE, DURABLE&#038;url=https:\/\/enaw.ch\/fr\/le-gout-de-lenergie-locale-durable\" target=\"_blank\"><span><i class=\"fa-brands fa-x-twitter\"><\/i><\/span><\/a>\n    <a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/enaw.ch\/fr\/le-gout-de-lenergie-locale-durable\" target=\"_blank\"><span><i class=\"fab fa-facebook-f\"><\/i><\/span><\/a>\n    <a href=\"https:\/\/api.whatsapp.com\/send?text=Recours au bois local via un chauffage \u00e0 distance, consommation de mazout divis\u00e9e par quatre, 10 % d\u00e9j\u00e0 de l\u2019\u00e9lectricit\u00e9 d\u2019origine solaire, le reste certifi\u00e9 hydraulique, froid pr\u00e9lev\u00e9 dans l\u2019environnement : \u00ab durable \u00bb prend plus d\u2019un sens chez Camille Bloch SA, dont les sp\u00e9cialit\u00e9s chocolati\u00e8res sont un succ\u00e8s jamais d\u00e9menti depuis les ann\u00e9es 1940. https:\/\/enaw.ch\/fr\/le-gout-de-lenergie-locale-durable\" target=\"_blank\"><span><i class=\"fab fa-whatsapp\"><\/i><\/span><\/a>\n    <a href=\"mailto:?subject=LE GO\u00dbT DE L\u2019\u00c9NERGIE LOCALE, DURABLE&#038;body=Recours au bois local via un chauffage \u00e0 distance, consommation de mazout divis\u00e9e par quatre, 10 % d\u00e9j\u00e0 de l\u2019\u00e9lectricit\u00e9 d\u2019origine solaire, le reste certifi\u00e9 hydraulique, froid pr\u00e9lev\u00e9 dans l\u2019environnement : \u00ab durable \u00bb prend plus d\u2019un sens chez Camille Bloch SA, dont les sp\u00e9cialit\u00e9s chocolati\u00e8res sont un succ\u00e8s jamais d\u00e9menti depuis les ann\u00e9es 1940. https:\/\/enaw.ch\/fr\/le-gout-de-lenergie-locale-durable\" target=\"_blank\"><span><i class=\"fas fa-envelope\"><\/i><\/span><\/a>\n<\/div>\n        <\/div>\n    <\/section>\n\n    <div class=\"single-post-section-triger-end\"><\/div>\n\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n    <div class=\"sidebar-content scrollMagic-block visibleInBackend\" data-uid=\"6a574e5dae626\">\n        \n        \n    <div class=\"popular-post-block\">\n        <h3>Articles les plus lus<\/h3>\n\n                                            \n<a href=\"https:\/\/enaw.ch\/fr\/material-schnell-check-firmen-gesucht\" class=\"post-card post-card-sidebar-29884 scrollMagic-block visibleInBackend\" data-uid=\"6a574e5db5baf\" id=\"29884\">\n            <div class=\"post-photo\" style=\"background-image: url(https:\/\/enaw.ch\/wp-content\/uploads\/2026\/03\/Materialkreislauf_Adobe-1200x800.jpeg);\">\n            <img decoding=\"async\" src=\"https:\/\/enaw.ch\/wp-content\/themes\/enaw_v2\/assets\/images\/post_card_sidebar.png\" alt=\"Nous recherchons des entreprises pour notre check-up mat\u00e9riaux rapide\u00a0\" \/>\n        <\/div>\n    \n    <div class=\"post-info\">\n        <div class=\"post-tags\">\n                                    \n        <div class=\"tag  \">Actualit\u00e9<\/div>    <div class=\"tag  \">Efficacit\u00e9 des ressources<\/div>    <div class=\"tag  \">Zurich<\/div>\n\n        <\/div>\n\n        <p class=\"post-date\">27.03.2026<\/p>\n\n        <h4 class=\"margin-bottom-0\">Nous recherchons des entreprises pour notre check-up mat\u00e9riaux rapide\u00a0<\/h4>\n    <\/div>\n<\/a>\n\n            <\/div>\n\n        <div class=\"facts-block\">\n    <div class=\"facts-content\">\n        <h4 class=\"text-white text-align-center\">Faits<\/h4>\n\n                    <p class=\"fact-title margin-bottom-0 text-blue-light text-align-center\">L&rsquo; ESSENTIEL EN BREF<\/p>\n        \n        \n                    <div class=\"facts-list  \">\n                                    <div>\n                        <p class=\"margin-bottom-0 text-white small\">La chocolaterie Camille Bloch SA produit annuellement 3500 tonnes de chocolat. Ce qui exige de l\u2019\u00e9nergie !<\/p>\n                        <p class=\"margin-bottom-0 text-white small\"><\/p>\n                    <\/div>\n                                    <div>\n                        <p class=\"margin-bottom-0 text-white small\">Sa longue tradition de raffinement se retrouve dans ses solutions \u00e9nerg\u00e9tiques : b\u00e2timents avec de hautes exigences, cha\u00eene de production tr\u00e8s largement aliment\u00e9e par des sources renouvelables.<\/p>\n                        <p class=\"margin-bottom-0 text-white small\"><\/p>\n                    <\/div>\n                                    <div>\n                        <p class=\"margin-bottom-0 text-white small\">L\u2019engagement \u00e9nerg\u00e9tique remarquable de cette entreprise familiale s\u2019inscrit dans le cadre d\u2019une convention d\u2019objectifs conclue avec la Conf\u00e9d\u00e9ration avec l\u2019appui de l\u2019AEnEC.<\/p>\n                        <p class=\"margin-bottom-0 text-white small\"><\/p>\n                    <\/div>\n                            <\/div>\n            <\/div>\n<\/div>\n\n        \n            <\/div>\n\n<\/div>\n<\/div>\n\n\n\n                        <section class=\"related-posts-block block-paddings blue-light-bg\">\n                <div class=\"container-main\">\n                    <div class=\"title-block title-block-6a574e5db7c43\">\n                        <h2>Articles connexes<\/h2>\n                    <\/div>\n\n                    <div class=\"posts-cards scrollMagic-block visibleInBackend\" data-uid=\"6a574e5db7d14\">\n                                                                                    <div class=\"post-card-wrapper\">\n                                                                                                                                                \n<a href=\"https:\/\/enaw.ch\/fr\/alpe-fleurie\" class=\"post-card post-card-desk-30082 scrollMagic-block visibleInBackend\" data-uid=\"6a574e5db8017\" id=\"30082\">\n    \n            <div class=\"post-photo\" style=\"background-image: url(https:\/\/enaw.ch\/wp-content\/uploads\/2026\/05\/Alpe2-1200x917.jpg);\">\n            <img decoding=\"async\" src=\"https:\/\/enaw.ch\/wp-content\/themes\/enaw_v2\/assets\/images\/post_card_sidebar.png\" alt=\"Un h\u00f4tel r\u00e9solument sur la voie de la d\u00e9carbonation\" \/>\n        <\/div>\n    \n\n    <div class=\"post-info\">\n        <div class=\"post-tags\">\n                                    \n        <div class=\"tag  \">Actualit\u00e9<\/div>    <div class=\"tag  \">Exemples de r\u00e9alisations<\/div>    <div class=\"tag  \">Autres<\/div>    <div class=\"tag  \">Autres<\/div>    <div class=\"tag  \">Vaud<\/div>    <div class=\"tag  \">Restauration et h\u00f4tellerie<\/div>\n\n        <\/div>\n\n        <p class=\"post-date\">04.05.2026<\/p>\n\n        <h3>Un h\u00f4tel r\u00e9solument sur la voie de la d\u00e9carbonation<\/h3>\n\n        \n        <div class=\"btn-block\">\n            <div class=\"main-btn\">Lire plus<\/div>\n        <\/div>\n    <\/div>\n<\/a>                                <\/div>\n                                                                                                                <div class=\"post-card-wrapper\">\n                                                                                                                                                \n<a href=\"https:\/\/enaw.ch\/fr\/kundenspezifische-entwertung-fuer-herkunftsnachweise-fuer-biogas-bezug-2026\" class=\"post-card post-card-desk-29890 scrollMagic-block visibleInBackend\" data-uid=\"6a574e5db887b\" id=\"29890\">\n    \n            <div class=\"post-photo\" style=\"background-image: url(https:\/\/enaw.ch\/wp-content\/uploads\/2026\/03\/Biogas_Adobe-1200x840.jpeg);\">\n            <img decoding=\"async\" src=\"https:\/\/enaw.ch\/wp-content\/themes\/enaw_v2\/assets\/images\/post_card_sidebar.png\" alt=\"Achat de biogaz en 2026\u00a0: attribution des garanties d\u2019origine\" \/>\n        <\/div>\n    \n\n    <div class=\"post-info\">\n        <div class=\"post-tags\">\n                                    \n        <div class=\"tag  \">Actualit\u00e9<\/div>    <div class=\"tag  \">Tous<\/div>    <div class=\"tag  \">Berne<\/div>\n\n        <\/div>\n\n        <p class=\"post-date\">06.03.2026<\/p>\n\n        <h3>Achat de biogaz en 2026\u00a0: attribution des garanties d\u2019origine<\/h3>\n\n                    <p class=\"post-desc margin-bottom-0\">\n                Les entreprises (soumises \u00e0 un engagement de r\u00e9duction, au syst\u00e8me SEQE ou ayant une convention d&rsquo;objectifs sans engagement de r\u00e9duction) qui souhaitent comptabiliser l&rsquo;utilisation de combustibles renouvelables liquides et gazeux, par exemple biogaz, dans leur suivi annuel \u00e0 partir de 2025 avec un facteur d&rsquo;\u00e9mission nul, doivent disposer de garanties d&rsquo;origine (GO) et indiquer le num\u00e9ro de GO correspondant dans le suivi.            <\/p>\n        \n        <div class=\"btn-block\">\n            <div class=\"main-btn\">Lire plus<\/div>\n        <\/div>\n    <\/div>\n<\/a>                                <\/div>\n                                                                        <\/div>\n                <\/div>\n\n                            <\/section>\n            \n\n\n","protected":false},"excerpt":{"rendered":"<p>Recours au bois local via un chauffage \u00e0 distance, consommation de mazout divis\u00e9e par quatre, 10 % d\u00e9j\u00e0 de l\u2019\u00e9lectricit\u00e9 d\u2019origine solaire, le reste certifi\u00e9 hydraulique, froid pr\u00e9lev\u00e9 dans l\u2019environnement : \u00ab durable \u00bb prend plus d\u2019un sens chez Camille Bloch SA, dont les sp\u00e9cialit\u00e9s chocolati\u00e8res sont un succ\u00e8s jamais d\u00e9menti depuis les ann\u00e9es 1940. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10538,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[3],"tags":[],"kanton":[128],"thema":[218,209],"produkt":[222],"rubrik":[308],"branche":[275],"class_list":["post-7343","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","kanton-berne","thema-nouvelles-sources-denergie","thema-recuperation-de-chaleur","produkt-modele-energie","rubrik-exemples-de-realisations","branche-production-de-denrees-alimentaires"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>LE GO\u00dbT DE L\u2019\u00c9NERGIE LOCALE, DURABLE | Agence de l\u2019\u00e9nergie pour l\u2019\u00e9conomie<\/title>\n<meta name=\"description\" content=\"Seit 2001 setzen wir gemeinsam mit den Unternehmen auf wirtschaftlichen Klimaschutz. Wir bieten individuelle L\u00f6sungen, um die Energie- und Ressourceneffizienz kontinuierlich zu steigern. Unsere 126 EnAW-Beraterinnen und EnAW-Berater kennen sich in allen Branchen und Wirtschaftszweigen aus und begleiten auch Ihr Unternehmen kompetent auf dem Weg zu weniger CO2, tieferen Kosten und mehr Energie- und Ressourceneffizienz.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/enaw.ch\/fr\/le-gout-de-lenergie-locale-durable\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LE GO\u00dbT DE L\u2019\u00c9NERGIE LOCALE, DURABLE\" \/>\n<meta property=\"og:description\" content=\"Seit 2001 setzen wir gemeinsam mit den Unternehmen auf wirtschaftlichen Klimaschutz. Wir bieten individuelle L\u00f6sungen, um die Energie- und Ressourceneffizienz kontinuierlich zu steigern. Unsere 126 EnAW-Beraterinnen und EnAW-Berater kennen sich in allen Branchen und Wirtschaftszweigen aus und begleiten auch Ihr Unternehmen kompetent auf dem Weg zu weniger CO2, tieferen Kosten und mehr Energie- und Ressourceneffizienz.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/enaw.ch\/fr\/le-gout-de-lenergie-locale-durable\" \/>\n<meta property=\"og:site_name\" content=\"Agence de l\u2019\u00e9nergie pour l\u2019\u00e9conomie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/enaw.aenec\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-25T21:20:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-08T15:12:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/enaw.ch\/wp-content\/uploads\/2020\/02\/enaw_header_camille-600x200.png\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"berta_admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@info_enaw\" \/>\n<meta name=\"twitter:site\" content=\"@info_enaw\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"berta_admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/enaw.ch\\\/fr\\\/le-gout-de-lenergie-locale-durable#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/enaw.ch\\\/fr\\\/le-gout-de-lenergie-locale-durable\"},\"author\":{\"name\":\"berta_admin\",\"@id\":\"https:\\\/\\\/enaw.ch\\\/#\\\/schema\\\/person\\\/960a0d1bce57ca722ef3b56c23b165e8\"},\"headline\":\"LE GO\u00dbT DE L\u2019\u00c9NERGIE LOCALE, DURABLE\",\"datePublished\":\"2020-02-25T21:20:00+00:00\",\"dateModified\":\"2023-06-08T15:12:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/enaw.ch\\\/fr\\\/le-gout-de-lenergie-locale-durable\"},\"wordCount\":1029,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/enaw.ch\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/enaw.ch\\\/fr\\\/le-gout-de-lenergie-locale-durable#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/enaw.ch\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/enaw_header_camille.png\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/enaw.ch\\\/fr\\\/le-gout-de-lenergie-locale-durable\",\"url\":\"https:\\\/\\\/enaw.ch\\\/fr\\\/le-gout-de-lenergie-locale-durable\",\"name\":\"LE GO\u00dbT DE L\u2019\u00c9NERGIE LOCALE, DURABLE | Agence de l\u2019\u00e9nergie pour l\u2019\u00e9conomie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/enaw.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/enaw.ch\\\/fr\\\/le-gout-de-lenergie-locale-durable#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/enaw.ch\\\/fr\\\/le-gout-de-lenergie-locale-durable#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/enaw.ch\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/enaw_header_camille.png\",\"datePublished\":\"2020-02-25T21:20:00+00:00\",\"dateModified\":\"2023-06-08T15:12:33+00:00\",\"description\":\"Seit 2001 setzen wir gemeinsam mit den Unternehmen auf wirtschaftlichen Klimaschutz. Wir bieten individuelle L\u00f6sungen, um die Energie- und Ressourceneffizienz kontinuierlich zu steigern. Unsere 126 EnAW-Beraterinnen und EnAW-Berater kennen sich in allen Branchen und Wirtschaftszweigen aus und begleiten auch Ihr Unternehmen kompetent auf dem Weg zu weniger CO2, tieferen Kosten und mehr Energie- und Ressourceneffizienz.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/enaw.ch\\\/fr\\\/le-gout-de-lenergie-locale-durable#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/enaw.ch\\\/fr\\\/le-gout-de-lenergie-locale-durable\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/enaw.ch\\\/fr\\\/le-gout-de-lenergie-locale-durable#primaryimage\",\"url\":\"https:\\\/\\\/enaw.ch\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/enaw_header_camille.png\",\"contentUrl\":\"https:\\\/\\\/enaw.ch\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/enaw_header_camille.png\",\"width\":1200,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/enaw.ch\\\/fr\\\/le-gout-de-lenergie-locale-durable#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/enaw.ch\\\/fr\\\/beispiel-seite\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LE GO\u00dbT DE L\u2019\u00c9NERGIE LOCALE, DURABLE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/enaw.ch\\\/#website\",\"url\":\"https:\\\/\\\/enaw.ch\\\/\",\"name\":\"Energie-Agentur der Wirtschaft\",\"description\":\"Un autre site web WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/enaw.ch\\\/#organization\"},\"alternateName\":\"EnAW\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/enaw.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/enaw.ch\\\/#organization\",\"name\":\"EnAW Energie-Agentur der Wirtschaft\",\"alternateName\":\"EnAW\",\"url\":\"https:\\\/\\\/enaw.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/enaw.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/enaw.ch\\\/wp-content\\\/uploads\\\/Logos\\\/EnAW_Logo_DE_RGB_black-1.svg\",\"contentUrl\":\"https:\\\/\\\/enaw.ch\\\/wp-content\\\/uploads\\\/Logos\\\/EnAW_Logo_DE_RGB_black-1.svg\",\"width\":219,\"height\":38,\"caption\":\"EnAW Energie-Agentur der Wirtschaft\"},\"image\":{\"@id\":\"https:\\\/\\\/enaw.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/enaw.aenec\",\"https:\\\/\\\/x.com\\\/info_enaw\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/enaw\\\/\"],\"description\":\"Seit 2001 setzen wir gemeinsam mit den Unternehmen auf wirtschaftlichen Klimaschutz. Wir bieten individuelle L\u00f6sungen, um die Energie- und Ressourceneffizienz kontinuierlich zu steigern. Unsere 126 EnAW-Beraterinnen und EnAW-Berater kennen sich in allen Branchen und Wirtschaftszweigen aus und begleiten auch Ihr Unternehmen kompetent auf dem Weg zu weniger CO2, tieferen Kosten und mehr Energie- und Ressourceneffizienz.\",\"email\":\"news@enaw.ch\",\"telephone\":\"+41 44 388 24 24\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/enaw.ch\\\/#\\\/schema\\\/person\\\/960a0d1bce57ca722ef3b56c23b165e8\",\"name\":\"berta_admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba69f50d7a1a9d3e8396e388b28c0ef88c2e80dea9cdf768565f4508b567ad84?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba69f50d7a1a9d3e8396e388b28c0ef88c2e80dea9cdf768565f4508b567ad84?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba69f50d7a1a9d3e8396e388b28c0ef88c2e80dea9cdf768565f4508b567ad84?s=96&d=mm&r=g\",\"caption\":\"berta_admin\"},\"sameAs\":[\"http:\\\/\\\/dev.enaw-v2.bertastrasse1.ch\"],\"url\":\"https:\\\/\\\/enaw.ch\\\/fr\\\/author\\\/berta_admin\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"LE GO\u00dbT DE L\u2019\u00c9NERGIE LOCALE, DURABLE | Agence de l\u2019\u00e9nergie pour l\u2019\u00e9conomie","description":"Seit 2001 setzen wir gemeinsam mit den Unternehmen auf wirtschaftlichen Klimaschutz. Wir bieten individuelle L\u00f6sungen, um die Energie- und Ressourceneffizienz kontinuierlich zu steigern. Unsere 126 EnAW-Beraterinnen und EnAW-Berater kennen sich in allen Branchen und Wirtschaftszweigen aus und begleiten auch Ihr Unternehmen kompetent auf dem Weg zu weniger CO2, tieferen Kosten und mehr Energie- und Ressourceneffizienz.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/enaw.ch\/fr\/le-gout-de-lenergie-locale-durable","og_locale":"fr_FR","og_type":"article","og_title":"LE GO\u00dbT DE L\u2019\u00c9NERGIE LOCALE, DURABLE","og_description":"Seit 2001 setzen wir gemeinsam mit den Unternehmen auf wirtschaftlichen Klimaschutz. Wir bieten individuelle L\u00f6sungen, um die Energie- und Ressourceneffizienz kontinuierlich zu steigern. Unsere 126 EnAW-Beraterinnen und EnAW-Berater kennen sich in allen Branchen und Wirtschaftszweigen aus und begleiten auch Ihr Unternehmen kompetent auf dem Weg zu weniger CO2, tieferen Kosten und mehr Energie- und Ressourceneffizienz.","og_url":"https:\/\/enaw.ch\/fr\/le-gout-de-lenergie-locale-durable","og_site_name":"Agence de l\u2019\u00e9nergie pour l\u2019\u00e9conomie","article_publisher":"https:\/\/www.facebook.com\/enaw.aenec","article_published_time":"2020-02-25T21:20:00+00:00","article_modified_time":"2023-06-08T15:12:33+00:00","og_image":[{"url":"https:\/\/enaw.ch\/wp-content\/uploads\/2020\/02\/enaw_header_camille-600x200.png","type":"image\/png","width":"","height":""}],"author":"berta_admin","twitter_card":"summary_large_image","twitter_creator":"@info_enaw","twitter_site":"@info_enaw","twitter_misc":{"\u00c9crit par":"berta_admin","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/enaw.ch\/fr\/le-gout-de-lenergie-locale-durable#article","isPartOf":{"@id":"https:\/\/enaw.ch\/fr\/le-gout-de-lenergie-locale-durable"},"author":{"name":"berta_admin","@id":"https:\/\/enaw.ch\/#\/schema\/person\/960a0d1bce57ca722ef3b56c23b165e8"},"headline":"LE GO\u00dbT DE L\u2019\u00c9NERGIE LOCALE, DURABLE","datePublished":"2020-02-25T21:20:00+00:00","dateModified":"2023-06-08T15:12:33+00:00","mainEntityOfPage":{"@id":"https:\/\/enaw.ch\/fr\/le-gout-de-lenergie-locale-durable"},"wordCount":1029,"commentCount":0,"publisher":{"@id":"https:\/\/enaw.ch\/#organization"},"image":{"@id":"https:\/\/enaw.ch\/fr\/le-gout-de-lenergie-locale-durable#primaryimage"},"thumbnailUrl":"https:\/\/enaw.ch\/wp-content\/uploads\/2020\/02\/enaw_header_camille.png","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/enaw.ch\/fr\/le-gout-de-lenergie-locale-durable","url":"https:\/\/enaw.ch\/fr\/le-gout-de-lenergie-locale-durable","name":"LE GO\u00dbT DE L\u2019\u00c9NERGIE LOCALE, DURABLE | Agence de l\u2019\u00e9nergie pour l\u2019\u00e9conomie","isPartOf":{"@id":"https:\/\/enaw.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/enaw.ch\/fr\/le-gout-de-lenergie-locale-durable#primaryimage"},"image":{"@id":"https:\/\/enaw.ch\/fr\/le-gout-de-lenergie-locale-durable#primaryimage"},"thumbnailUrl":"https:\/\/enaw.ch\/wp-content\/uploads\/2020\/02\/enaw_header_camille.png","datePublished":"2020-02-25T21:20:00+00:00","dateModified":"2023-06-08T15:12:33+00:00","description":"Seit 2001 setzen wir gemeinsam mit den Unternehmen auf wirtschaftlichen Klimaschutz. Wir bieten individuelle L\u00f6sungen, um die Energie- und Ressourceneffizienz kontinuierlich zu steigern. Unsere 126 EnAW-Beraterinnen und EnAW-Berater kennen sich in allen Branchen und Wirtschaftszweigen aus und begleiten auch Ihr Unternehmen kompetent auf dem Weg zu weniger CO2, tieferen Kosten und mehr Energie- und Ressourceneffizienz.","breadcrumb":{"@id":"https:\/\/enaw.ch\/fr\/le-gout-de-lenergie-locale-durable#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/enaw.ch\/fr\/le-gout-de-lenergie-locale-durable"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/enaw.ch\/fr\/le-gout-de-lenergie-locale-durable#primaryimage","url":"https:\/\/enaw.ch\/wp-content\/uploads\/2020\/02\/enaw_header_camille.png","contentUrl":"https:\/\/enaw.ch\/wp-content\/uploads\/2020\/02\/enaw_header_camille.png","width":1200,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/enaw.ch\/fr\/le-gout-de-lenergie-locale-durable#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/enaw.ch\/fr\/beispiel-seite"},{"@type":"ListItem","position":2,"name":"LE GO\u00dbT DE L\u2019\u00c9NERGIE LOCALE, DURABLE"}]},{"@type":"WebSite","@id":"https:\/\/enaw.ch\/#website","url":"https:\/\/enaw.ch\/","name":"Energie-Agentur der Wirtschaft","description":"Un autre site web WordPress","publisher":{"@id":"https:\/\/enaw.ch\/#organization"},"alternateName":"EnAW","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/enaw.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/enaw.ch\/#organization","name":"EnAW Energie-Agentur der Wirtschaft","alternateName":"EnAW","url":"https:\/\/enaw.ch\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/enaw.ch\/#\/schema\/logo\/image\/","url":"https:\/\/enaw.ch\/wp-content\/uploads\/Logos\/EnAW_Logo_DE_RGB_black-1.svg","contentUrl":"https:\/\/enaw.ch\/wp-content\/uploads\/Logos\/EnAW_Logo_DE_RGB_black-1.svg","width":219,"height":38,"caption":"EnAW Energie-Agentur der Wirtschaft"},"image":{"@id":"https:\/\/enaw.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/enaw.aenec","https:\/\/x.com\/info_enaw","https:\/\/www.linkedin.com\/company\/enaw\/"],"description":"Seit 2001 setzen wir gemeinsam mit den Unternehmen auf wirtschaftlichen Klimaschutz. Wir bieten individuelle L\u00f6sungen, um die Energie- und Ressourceneffizienz kontinuierlich zu steigern. Unsere 126 EnAW-Beraterinnen und EnAW-Berater kennen sich in allen Branchen und Wirtschaftszweigen aus und begleiten auch Ihr Unternehmen kompetent auf dem Weg zu weniger CO2, tieferen Kosten und mehr Energie- und Ressourceneffizienz.","email":"news@enaw.ch","telephone":"+41 44 388 24 24"},{"@type":"Person","@id":"https:\/\/enaw.ch\/#\/schema\/person\/960a0d1bce57ca722ef3b56c23b165e8","name":"berta_admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/ba69f50d7a1a9d3e8396e388b28c0ef88c2e80dea9cdf768565f4508b567ad84?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ba69f50d7a1a9d3e8396e388b28c0ef88c2e80dea9cdf768565f4508b567ad84?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ba69f50d7a1a9d3e8396e388b28c0ef88c2e80dea9cdf768565f4508b567ad84?s=96&d=mm&r=g","caption":"berta_admin"},"sameAs":["http:\/\/dev.enaw-v2.bertastrasse1.ch"],"url":"https:\/\/enaw.ch\/fr\/author\/berta_admin"}]}},"_links":{"self":[{"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/posts\/7343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/comments?post=7343"}],"version-history":[{"count":0,"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/posts\/7343\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/media\/10538"}],"wp:attachment":[{"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/media?parent=7343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/categories?post=7343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/tags?post=7343"},{"taxonomy":"kanton","embeddable":true,"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/kanton?post=7343"},{"taxonomy":"thema","embeddable":true,"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/thema?post=7343"},{"taxonomy":"produkt","embeddable":true,"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/produkt?post=7343"},{"taxonomy":"rubrik","embeddable":true,"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/rubrik?post=7343"},{"taxonomy":"branche","embeddable":true,"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/branche?post=7343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}