{"id":6677,"date":"2022-05-04T14:54:00","date_gmt":"2022-05-04T12:54:00","guid":{"rendered":"https:\/\/enaw.ch\/eine-schoene-und-energiegeladene-mechanik\/"},"modified":"2023-08-24T08:31:06","modified_gmt":"2023-08-24T06:31:06","slug":"une-belle-mecanique-energetique","status":"publish","type":"post","link":"https:\/\/enaw.ch\/fr\/une-belle-mecanique-energetique","title":{"rendered":"UNE BELLE M\u00c9CANIQUE \u00c9NERG\u00c9TIQUE"},"content":{"rendered":"\n<div class=\"wp-block-columns is-style-block-with-sidebar is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"is-style-lead-paragraph wp-block-paragraph\">Breitling SA s&rsquo;est distingu\u00e9 en r\u00e9duisant de moiti\u00e9 la consommation \u00e9nerg\u00e9tique de sa manufacture de La Chaux-de-Fonds (NE), gr\u00e2ce notamment \u00e0 un judicieux \u00ab switch off \u00bb. Plus r\u00e9cemment, la marque horlog\u00e8re a int\u00e9gr\u00e9 \u00e0 son si\u00e8ge de Granges (SO) un d\u00e9partement d\u00e9di\u00e9 \u00e0 la durabilit\u00e9.<\/p>\n\n\n\n            <section class=\"container-media-slider-block block-paddings  \">\n            <div class=\"container-main\">\n                <div class=\"container-media-slider-content\">\n                    <div class=\"container-media-slider js-main-slider scrollMagic-block visibleInBackend\" data-uid=\"6a57332a79183\" data-nav=\"#container-media-slider-nav-6a57332a79183\" id=\"container-media-slider-6a57332a79183\">\n                                                    \n                            <div class=\"item-block\">\n                                                                                                                                                                \n                                \n                                                                                                            <div class=\"simple-image desk  \" style=\"background-image: url(https:\/\/enaw.ch\/wp-content\/uploads\/2022\/09\/eine_schone_und_energiegeladene_mechanik_1.jpeg)\"><\/div>\n\n                                        <div class=\"simple-image mob  \" style=\"background-image: url(https:\/\/enaw.ch\/wp-content\/uploads\/2022\/09\/eine_schone_und_energiegeladene_mechanik_1.jpeg)\"><\/div>\n                                                                    \n                                                            <\/div>\n                                                    \n                            <div class=\"item-block\">\n                                                                                                                                                                \n                                \n                                                                                                            <div class=\"simple-image desk  \" style=\"background-image: url(https:\/\/enaw.ch\/wp-content\/uploads\/2022\/09\/eine_schone_und_energiegeladene_mechanik_2.jpeg)\"><\/div>\n\n                                        <div class=\"simple-image mob  \" style=\"background-image: url(https:\/\/enaw.ch\/wp-content\/uploads\/2022\/09\/eine_schone_und_energiegeladene_mechanik_2.jpeg)\"><\/div>\n                                                                    \n                                                            <\/div>\n                                            <\/div>\n\n                    <div class=\"container-media-slider-nav js-nav-slider\" data-main=\"#container-media-slider-6a57332a79183\" id=\"container-media-slider-nav-6a57332a79183\">\n                                                                                    <div class=\"item-block\">\n                                    <p class=\"small margin-bottom-0\"> <\/p>\n                                <\/div>\n                                                                                                                <div class=\"item-block\">\n                                    <p class=\"small margin-bottom-0\">Fernand Moullet, responsable \u00c9nergie et technique de la manufacture<\/p>\n                                <\/div>\n                                                                        <\/div>\n\n                                    <\/div>\n            <\/div>\n        <\/section>\n    \n\n\n\n<p class=\"wp-block-paragraph\">Pour Fernand Moullet, responsable \u00c9nergie et technique de la manufacture chaux-de-fonni\u00e8re de Breitling SA, 2022 sera l\u2019ann\u00e9e de la retraite. Avec le sentiment du travail bien fait : les mesures \u00e9nerg\u00e9tiques qu\u2019il a d\u00e9ploy\u00e9es sur le site entre 2013 et 2018, en \u00e9troite complicit\u00e9 avec Yann Chapatte, le directeur financier d\u2019alors, continuent d\u2019accumuler leurs effets. Lesquels sont consid\u00e9rables, et c\u2019est peu dire lorsqu\u2019on passe d\u2019une consommation annuelle de 3&nbsp;300&nbsp;000 kWh \u00e0 1&nbsp;700&nbsp;000 kWh, soit une r\u00e9duction de 25&nbsp;% pour l\u2019\u00e9lectricit\u00e9 et de 75&nbsp;% pour le gaz.<\/p>\n\n\n\n                    <div id=\"r6a57332a79537\" class=\"default-single-post-title show-in-sidebar-menu\">\n                <h4>D\u00c9BUSQUER L\u2019INUTILE<\/h4>\n            <\/div>\n        \n\n\n\n<p class=\"wp-block-paragraph\">Avait-t-il fallu de gros investissements ? Non, du bon sens surtout. Ainsi, au sous-sol de la manufacture, cinq gros monoblocs de ventilation entretiennent dans les ateliers les conditions requises par le travail horloger, soit une temp\u00e9rature de 23 \u00b0C avec une humidit\u00e9 relative de 50&nbsp;%. Pour maintenir ces param\u00e8tres, il \u00e9tait prescrit initialement une ventilation ininterrompue. Pas convaincu, Fernand Moullet a exp\u00e9riment\u00e9 des arr\u00eats nocturnes. \u00ab&nbsp;J\u2019ai pu ainsi v\u00e9rifier que l\u2019excellente isolation de l\u2019usine garantissait la juste temp\u00e9rature et le bon taux d\u2019humidit\u00e9 dans les heures d\u2019activit\u00e9, malgr\u00e9 l\u2019arr\u00eat total de la ventilation entre 18 heures et 6 heures. Par la suite, la consommation de gaz, et donc les \u00e9missions de CO<sub>2<\/sub>, ont encore \u00e9t\u00e9 r\u00e9duites gr\u00e2ce au bouclage du circuit pour utiliser davantage d\u2019air recycl\u00e9, d\u00e9j\u00e0 chauff\u00e9.&nbsp;\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans ce m\u00eame esprit, Fernand Moullet a aussi abaiss\u00e9 la pression dans le circuit d\u2019air comprim\u00e9 de l\u2019usine de 11 \u00e0 6,5 bars. \u00ab C\u2019est suffisant pour la plupart des t\u00e2ches, un surpresseur pouvant servir localement une op\u00e9ration sp\u00e9cifique. Un bar en moins, c\u2019est 10&nbsp;% d\u2019\u00e9nergie \u00e9conomis\u00e9e. \u00bb<\/p>\n\n\n\n                    <div id=\"r6a57332a7969b\" class=\"default-single-post-title show-in-sidebar-menu\">\n                <h4>DES ROUAGES SANS CESSE POLIS<\/h4>\n            <\/div>\n        \n\n\n\n<p class=\"wp-block-paragraph\">Une m\u00eame optimisation m\u00e9ticuleuse, \u00ab horlog\u00e8re \u00bb, avait port\u00e9 sur le froid et le chaud n\u00e9cessaires \u00e0 tout atelier de m\u00e9canique. Elle se poursuit, poste par poste : r\u00e9cemment, c\u2019est l\u2019air chaud sur les lignes d\u2019assemblage qui a \u00e9t\u00e9 cibl\u00e9 pour \u00eatre r\u00e9cup\u00e9r\u00e9, pour le chauffage en hiver et pour la d\u00e9shumidification en \u00e9t\u00e9, un imp\u00e9ratif horloger.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De m\u00eame, les LED poursuivent aujourd\u2019hui leur conqu\u00eate des locaux : leur avantage est bien s\u00fbr leur faible consommation, mais elles d\u00e9gagent aussi moins de chaleur que les autres sources, et r\u00e9duisent la climatisation n\u00e9cessaire pour stabiliser la temp\u00e9rature des ateliers, d\u2019o\u00f9 une \u00e9conomie suppl\u00e9mentaire d\u2019\u00e9nergie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les ampoules et les tubes fluorescents chass\u00e9s par les LED ach\u00e8vent leur temps d\u2019usage dans des annexes peu utilis\u00e9es. \u00ab&nbsp;Cette solution prend en compte leur \u00e9nergie grise&nbsp;\u00bb, justifie Fernand Moullet, qui aime \u00e0 r\u00e9p\u00e9ter que \u00ab&nbsp;les petits ruisseaux font les grandes rivi\u00e8res.&nbsp;\u00bb Amusante formule chez quelqu\u2019un qui a aussi, \u00e0 l\u2019occasion, mu\u00e9 quelques \u00ab&nbsp;grandes rivi\u00e8res&nbsp;\u00bb en \u00ab&nbsp;petits ruisseaux&nbsp;\u00bb, pour des \u00e9conomies d\u2019eau consid\u00e9rables au niveau sanitaire, et m\u00eame \u00ab&nbsp;gigantesques&nbsp;\u00bb \u2013 dixit Fernand Moullet dans ses archives \u2013 lorsque les serveurs informatiques ont \u00e9t\u00e9 desservis en froid par un d\u00e9tour du circuit d\u2019eau de refroidissement de l\u2019usine.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enfin, Breitling SA ayant dot\u00e9 sa direction de Granges (SO) d\u2019un d\u00e9partement vou\u00e9 \u00e0 la durabilit\u00e9 et \u00e0 la d\u00e9carbonation en 2020, Fernand Moullet voit se pr\u00e9ciser son projet de centrale solaire photovolta\u00efque, touche finale \u00e0 une belle oeuvre. Et pour sa retraite, ce passionn\u00e9 de v\u00e9lo a d\u2019ores et d\u00e9j\u00e0 en t\u00eate de nouvelles performances environnementales : il entend notamment collecter les d\u00e9chets jet\u00e9s en bord de route, en cycliste recycleur.<\/p>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1068\" height=\"565\" data-id=\"5852\" src=\"https:\/\/enaw.ch\/wp-content\/uploads\/2022\/09\/breitling-SA-1-1.jpeg\" alt=\"\" class=\"wp-image-5852\" srcset=\"https:\/\/enaw.ch\/wp-content\/uploads\/2022\/09\/breitling-SA-1-1.jpeg 1068w, https:\/\/enaw.ch\/wp-content\/uploads\/2022\/09\/breitling-SA-1-1-600x317.jpeg 600w, https:\/\/enaw.ch\/wp-content\/uploads\/2022\/09\/breitling-SA-1-1-1024x542.jpeg 1024w, https:\/\/enaw.ch\/wp-content\/uploads\/2022\/09\/breitling-SA-1-1-768x406.jpeg 768w\" sizes=\"(max-width: 1068px) 100vw, 1068px\" \/><figcaption class=\"wp-element-caption\">Breitling SA, La Chaux-de-Fonds (NE)<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Fond\u00e9e en 1884 \u00e0 Saint-Imier (BE), la marque Breitling a pris ses quartiers \u00e0 La Chaux-de-Fonds (NE) d\u00e8s 1892. Elle a rapidement acquis une renomm\u00e9e de pr\u00e9cision et de fiabilit\u00e9 au service des sciences, de l\u2019industrie et des sports, puis de l\u2019aviation. Breitling SA est l\u2019une des rares marques \u00e0 \u00e9quiper tous ses mod\u00e8les de mouvements certifi\u00e9s chronom\u00e8tres, int\u00e9gralement con\u00e7us et fabriqu\u00e9s dans sa manufacture de La Chaux-de-Fonds. Dans son b\u00e2timent agrandi en 2007, qui abrite 200 collaborateurs, 150 horlogers et op\u00e9rateurs assurent la production de 200&nbsp;000 montres par an.<\/p>\n\n\n\n            <section class=\"infos-block block-paddings  \">\n            <div class=\"container-main\">\n\n                                                    <div class=\"title-block title-block-6a57332a7f26b scrollMagic-block visibleInBackend\" data-uid=\"6a57332a7f26d\">\n        \n                    <h2>Informations<\/h2>\n            <\/div>\n\n                \n                <div class=\"narrow-container\">\n                    <div class=\"infos\">\n\n                                                    <div class=\"info-block info-block-6a57332a7f271  scrollMagic-block visibleInBackend\" data-uid=\"6a57332a7f272\">\n\n                                \n                                                                    <div class=\" info-items\">\n                                            <div class=\" info-item\">\n        <svg width=\"40\" height=\"42\" viewBox=\"0 0 40 42\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n            <path d=\"M20.0034 2.25146V27.2515\" stroke=\"#99ABF2\" stroke-width=\"4\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n            <path d=\"M12.5034 19.7515L20.0034 27.2515L27.5034 19.7515\" stroke=\"#99ABF2\" stroke-width=\"4\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n            <path d=\"M26.2533 8.5H30C31.3261 8.5 32.5979 9.02678 33.5355 9.96447C34.4732 10.9021 35 12.1739 35 13.5V34.75C35 36.0761 34.4732 37.3479 33.5355 38.2855C32.5979 39.2232 31.3261 39.75 30 39.75H10C8.67392 39.75 7.40215 39.2232 6.46447 38.2855C5.52678 37.3479 5 36.0761 5 34.75V13.5C5 12.1739 5.52678 10.9021 6.46447 9.96447C7.40215 9.02678 8.67392 8.5 10 8.5H13.75\" stroke=\"#99ABF2\" stroke-width=\"4\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n        <\/svg>\n        <a href=\"https:\/\/enaw.ch\/wp-content\/uploads\/2022\/09\/enaw_magazin_doppelseiten_2021.pdf\" target=\"_blank\" class=\"heading-h4 margin-bottom-0\">Magazine \u00abFokus\u00bb 2021 (PDF)<\/a>\n    <\/div>\n    <div class=\" info-item\">\n        <svg width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n            <path d=\"M20.7151 29.2916L14.2826 35.724V35.724C11.9135 38.0919 8.0737 38.0919 5.70458 35.724L4.27566 34.2951V34.2951C1.90811 31.927 1.90811 28.0882 4.27566 25.7201L13.5674 16.4268V16.4268C15.9366 14.0589 19.7764 14.0589 22.1455 16.4268L23.5744 17.8572\" stroke=\"#99ABF2\" stroke-width=\"4\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n            <path d=\"M19.2846 10.7081L25.7171 4.27718V4.27718C28.0847 1.90842 31.9243 1.90749 34.2931 4.27511C34.2938 4.2758 34.2944 4.27649 34.2951 4.27718L35.7241 5.70457V5.70457C38.0916 8.07267 38.0916 11.9115 35.7241 14.2796L26.4323 23.5729V23.5729C24.0647 25.9417 20.225 25.9426 17.8563 23.575C17.8556 23.5743 17.8549 23.5736 17.8542 23.5729L16.4253 22.1425\" stroke=\"#99ABF2\" stroke-width=\"4\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n        <\/svg>\n        <a href=\"https:\/\/www.breitling.com\/ch-fr\/\" target=\"_blank\" class=\"heading-h4 margin-bottom-0\">Breitling SA<\/a>\n    <\/div>\n    <div class=\" info-item\">\n        <svg width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n            <path d=\"M20.7151 29.2916L14.2826 35.724V35.724C11.9135 38.0919 8.0737 38.0919 5.70458 35.724L4.27566 34.2951V34.2951C1.90811 31.927 1.90811 28.0882 4.27566 25.7201L13.5674 16.4268V16.4268C15.9366 14.0589 19.7764 14.0589 22.1455 16.4268L23.5744 17.8572\" stroke=\"#99ABF2\" stroke-width=\"4\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n            <path d=\"M19.2846 10.7081L25.7171 4.27718V4.27718C28.0847 1.90842 31.9243 1.90749 34.2931 4.27511C34.2938 4.2758 34.2944 4.27649 34.2951 4.27718L35.7241 5.70457V5.70457C38.0916 8.07267 38.0916 11.9115 35.7241 14.2796L26.4323 23.5729V23.5729C24.0647 25.9417 20.225 25.9426 17.8563 23.575C17.8556 23.5743 17.8549 23.5736 17.8542 23.5729L16.4253 22.1425\" stroke=\"#99ABF2\" stroke-width=\"4\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n        <\/svg>\n        <a href=\"https:\/\/www.breitling.com\/ch-fr\/sustainability\/\" target=\"_blank\" class=\"heading-h4 margin-bottom-0\">Breitling SA Sustainability<\/a>\n    <\/div>\n                                    <\/div>\n                                \n                                \n                                \n                                                            <\/div>\n                        \n                    <\/div>\n                <\/div>\n            <\/div>\n\n                    <\/section>\n    \n\n\n\n    <section class=\"share-links-block share-links-block-section scrollMagic-block visibleInBackend\" data-uid=\"6a57332a7f406\">\n        <div class=\"container-main\">\n                        \n<div class=\"share-links\">\n    <a href=\"http:\/\/www.linkedin.com\/shareArticle?mini=true&amp;url=https:\/\/enaw.ch\/fr\/une-belle-mecanique-energetique&amp;title=UNE BELLE M\u00c9CANIQUE \u00c9NERG\u00c9TIQUE&amp;summary=Breitling SA s'est distingu\u00e9 en r\u00e9duisant de moiti\u00e9 la consommation \u00e9nerg\u00e9tique de sa manufacture de La Chaux-de-Fonds (NE), gr\u00e2ce notamment \u00e0 un judicieux \u00ab switch off \u00bb. Plus r\u00e9cemment, la marque horlog\u00e8re a int\u00e9gr\u00e9 \u00e0 son si\u00e8ge de Granges (SO) un d\u00e9partement d\u00e9di\u00e9 \u00e0 la durabilit\u00e9.\" target=\"_blank\"><span><i class=\"fab fa-linkedin-in\"><\/i><\/span><\/a>\n    <a href=\"https:\/\/twitter.com\/intent\/tweet?text=UNE BELLE M\u00c9CANIQUE \u00c9NERG\u00c9TIQUE&#038;url=https:\/\/enaw.ch\/fr\/une-belle-mecanique-energetique\" target=\"_blank\"><span><i class=\"fa-brands fa-x-twitter\"><\/i><\/span><\/a>\n    <a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/enaw.ch\/fr\/une-belle-mecanique-energetique\" target=\"_blank\"><span><i class=\"fab fa-facebook-f\"><\/i><\/span><\/a>\n    <a href=\"https:\/\/api.whatsapp.com\/send?text=Breitling SA s'est distingu\u00e9 en r\u00e9duisant de moiti\u00e9 la consommation \u00e9nerg\u00e9tique de sa manufacture de La Chaux-de-Fonds (NE), gr\u00e2ce notamment \u00e0 un judicieux \u00ab switch off \u00bb. Plus r\u00e9cemment, la marque horlog\u00e8re a int\u00e9gr\u00e9 \u00e0 son si\u00e8ge de Granges (SO) un d\u00e9partement d\u00e9di\u00e9 \u00e0 la durabilit\u00e9. https:\/\/enaw.ch\/fr\/une-belle-mecanique-energetique\" target=\"_blank\"><span><i class=\"fab fa-whatsapp\"><\/i><\/span><\/a>\n    <a href=\"mailto:?subject=UNE BELLE M\u00c9CANIQUE \u00c9NERG\u00c9TIQUE&#038;body=Breitling SA s'est distingu\u00e9 en r\u00e9duisant de moiti\u00e9 la consommation \u00e9nerg\u00e9tique de sa manufacture de La Chaux-de-Fonds (NE), gr\u00e2ce notamment \u00e0 un judicieux \u00ab switch off \u00bb. Plus r\u00e9cemment, la marque horlog\u00e8re a int\u00e9gr\u00e9 \u00e0 son si\u00e8ge de Granges (SO) un d\u00e9partement d\u00e9di\u00e9 \u00e0 la durabilit\u00e9. https:\/\/enaw.ch\/fr\/une-belle-mecanique-energetique\" target=\"_blank\"><span><i class=\"fas fa-envelope\"><\/i><\/span><\/a>\n<\/div>\n        <\/div>\n    <\/section>\n\n    <div class=\"single-post-section-triger-end\"><\/div>\n\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n    <div class=\"sidebar-content scrollMagic-block visibleInBackend\" data-uid=\"6a57332a7f912\">\n        \n        \n    <div class=\"popular-post-block\">\n        <h3>Articles les plus lus<\/h3>\n\n                                            \n<a href=\"https:\/\/enaw.ch\/fr\/material-schnell-check-firmen-gesucht\" class=\"post-card post-card-sidebar-29884 scrollMagic-block visibleInBackend\" data-uid=\"6a57332a8aeed\" id=\"29884\">\n            <div class=\"post-photo\" style=\"background-image: url(https:\/\/enaw.ch\/wp-content\/uploads\/2026\/03\/Materialkreislauf_Adobe-1200x800.jpeg);\">\n            <img decoding=\"async\" src=\"https:\/\/enaw.ch\/wp-content\/themes\/enaw_v2\/assets\/images\/post_card_sidebar.png\" alt=\"Nous recherchons des entreprises pour notre check-up mat\u00e9riaux rapide\u00a0\" \/>\n        <\/div>\n    \n    <div class=\"post-info\">\n        <div class=\"post-tags\">\n                                    \n        <div class=\"tag  \">Actualit\u00e9<\/div>    <div class=\"tag  \">Efficacit\u00e9 des ressources<\/div>    <div class=\"tag  \">Zurich<\/div>\n\n        <\/div>\n\n        <p class=\"post-date\">27.03.2026<\/p>\n\n        <h4 class=\"margin-bottom-0\">Nous recherchons des entreprises pour notre check-up mat\u00e9riaux rapide\u00a0<\/h4>\n    <\/div>\n<\/a>\n\n            <\/div>\n\n        \n        \n            <\/div>\n\n<\/div>\n<\/div>\n\n\n\n                        <section class=\"related-posts-block block-paddings blue-light-bg\">\n                <div class=\"container-main\">\n                    <div class=\"title-block title-block-6a57332ac05ea\">\n                        <h2>Articles connexes<\/h2>\n                    <\/div>\n\n                    <div class=\"posts-cards scrollMagic-block visibleInBackend\" data-uid=\"6a57332ac0717\">\n                                                                                    <div class=\"post-card-wrapper\">\n                                                                                                                                                \n<a href=\"https:\/\/enaw.ch\/fr\/dekarbonisierung-der-fuer-die-pommes-frites-herstellung-erforderlichen-waerme\" class=\"post-card post-card-desk-29610 scrollMagic-block visibleInBackend\" data-uid=\"6a57332ac4fc5\" id=\"29610\">\n    \n            <div class=\"post-photo\" style=\"background-image: url(https:\/\/enaw.ch\/wp-content\/uploads\/2026\/01\/frites_tueten_uebersicht_klein-1200x846.jpg);\">\n            <img decoding=\"async\" src=\"https:\/\/enaw.ch\/wp-content\/themes\/enaw_v2\/assets\/images\/post_card_sidebar.png\" alt=\"D\u00e9carboner la chaleur n\u00e9cessaire \u00e0 la production de frites\" \/>\n        <\/div>\n    \n\n    <div class=\"post-info\">\n        <div class=\"post-tags\">\n                                    \n        <div class=\"tag  \">Exemples de r\u00e9alisations<\/div>    <div class=\"tag  \">Plan D\u00e9carbonation<\/div>    <div class=\"tag  \">Neuch\u00e2tel<\/div>    <div class=\"tag  \">Production de denr\u00e9es alimentaires<\/div>\n\n        <\/div>\n\n        <p class=\"post-date\">15.01.2026<\/p>\n\n        <h3>D\u00e9carboner la chaleur n\u00e9cessaire \u00e0 la production de frites<\/h3>\n\n                    <p class=\"post-desc margin-bottom-0\">\n                Le site de frigemo SA \u00e0 Cressier (NE), qui fait partie du groupe fenaco, voit passer annuellement plus de 60\u00a0000 tonnes de pommes-de-terre pour sa production de frites congel\u00e9es. Avec en ligne de mire la neutralit\u00e9 carbone\u00a0: la planification est engag\u00e9e dans le sillage du \u00ab\u00a0Plan D\u00e9carbonation\u00a0\u00bb de l\u2019AEnEC.            <\/p>\n        \n        <div class=\"btn-block\">\n            <div class=\"main-btn\">Lire plus<\/div>\n        <\/div>\n    <\/div>\n<\/a>                                <\/div>\n                                                                                                                <div class=\"post-card-wrapper\">\n                                                                                                                                                \n<a href=\"https:\/\/enaw.ch\/fr\/ee\" class=\"post-card post-card-desk-28147 scrollMagic-block visibleInBackend\" data-uid=\"6a57332aca0eb\" id=\"28147\">\n    \n            <div class=\"post-photo\" style=\"background-image: url(https:\/\/enaw.ch\/wp-content\/uploads\/2025\/09\/AEnEC_VEZZINI_01-1200x675.png);\">\n            <img decoding=\"async\" src=\"https:\/\/enaw.ch\/wp-content\/themes\/enaw_v2\/assets\/images\/post_card_sidebar.png\" alt=\"Entra\u00eenements \u00e9lectriques\u00a0: l\u2019approche syst\u00e9mique paie\u00a0!\" \/>\n        <\/div>\n    \n\n    <div class=\"post-info\">\n        <div class=\"post-tags\">\n                                    \n        <div class=\"tag  \">Autres<\/div>    <div class=\"tag  \">Partenaire<\/div>    <div class=\"tag  \">Mod\u00e8le \u00e9nergie<\/div>    <div class=\"tag  \">Mod\u00e8le PME<\/div>    <div class=\"tag  \">Optimisation de l&#039;exploitation<\/div>\n\n        <\/div>\n\n        <p class=\"post-date\">11.09.2025<\/p>\n\n        <h3>Entra\u00eenements \u00e9lectriques\u00a0: l\u2019approche syst\u00e9mique paie\u00a0!<\/h3>\n\n                    <p class=\"post-desc margin-bottom-0\">\n                Un professeur de Haute \u00e9cole sp\u00e9cialis\u00e9e et un conseiller AEnEC vous parlent ci-apr\u00e8s d\u2019un gisement important d\u2019\u00e9conomies d\u2019\u00e9lectricit\u00e9, qu\u2019un programme f\u00e9d\u00e9ral incite\u00a0\u2013 c\u2019est son nom, INCITE\u00a0\u2013 \u00e0 exploiter r\u00e9solument.            <\/p>\n        \n        <div class=\"btn-block\">\n            <div class=\"main-btn\">Lire plus<\/div>\n        <\/div>\n    <\/div>\n<\/a>                                <\/div>\n                                                                        <\/div>\n                <\/div>\n\n                            <\/section>\n            \n\n\n","protected":false},"excerpt":{"rendered":"<p>Breitling SA s&rsquo;est distingu\u00e9 en r\u00e9duisant de moiti\u00e9 la consommation \u00e9nerg\u00e9tique de sa manufacture de La Chaux-de-Fonds (NE), gr\u00e2ce notamment \u00e0 un judicieux \u00ab switch off \u00bb. Plus r\u00e9cemment, la marque horlog\u00e8re a int\u00e9gr\u00e9 \u00e0 son si\u00e8ge de Granges (SO) un d\u00e9partement d\u00e9di\u00e9 \u00e0 la durabilit\u00e9. Pour Fernand Moullet, responsable \u00c9nergie et technique de la [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":10690,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[3],"tags":[],"kanton":[145,137],"thema":[218,210],"produkt":[223],"rubrik":[203],"branche":[400],"class_list":["post-6677","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","kanton-neuchatel","kanton-soleure","thema-nouvelles-sources-denergie","thema-optimisation-de-lexploitation","produkt-modele-pme","rubrik-administration-et-politique","branche-horlogerie"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>UNE BELLE M\u00c9CANIQUE \u00c9NERG\u00c9TIQUE | Agence de l\u2019\u00e9nergie pour l\u2019\u00e9conomie<\/title>\n<meta name=\"description\" content=\"Seit 2001 setzen wir gemeinsam mit den Unternehmen auf wirtschaftlichen Klimaschutz. Wir bieten individuelle L\u00f6sungen, um die Energie- und Ressourceneffizienz kontinuierlich zu steigern. Unsere 126 EnAW-Beraterinnen und EnAW-Berater kennen sich in allen Branchen und Wirtschaftszweigen aus und begleiten auch Ihr Unternehmen kompetent auf dem Weg zu weniger CO2, tieferen Kosten und mehr Energie- und Ressourceneffizienz.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/enaw.ch\/fr\/une-belle-mecanique-energetique\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UNE BELLE M\u00c9CANIQUE \u00c9NERG\u00c9TIQUE\" \/>\n<meta property=\"og:description\" content=\"Seit 2001 setzen wir gemeinsam mit den Unternehmen auf wirtschaftlichen Klimaschutz. Wir bieten individuelle L\u00f6sungen, um die Energie- und Ressourceneffizienz kontinuierlich zu steigern. Unsere 126 EnAW-Beraterinnen und EnAW-Berater kennen sich in allen Branchen und Wirtschaftszweigen aus und begleiten auch Ihr Unternehmen kompetent auf dem Weg zu weniger CO2, tieferen Kosten und mehr Energie- und Ressourceneffizienz.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/enaw.ch\/fr\/une-belle-mecanique-energetique\" \/>\n<meta property=\"og:site_name\" content=\"Agence de l\u2019\u00e9nergie pour l\u2019\u00e9conomie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/enaw.aenec\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-04T12:54:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-24T06:31:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/enaw.ch\/wp-content\/uploads\/2022\/05\/enaw_header_breitling_22-600x200.png\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"nina.b\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@info_enaw\" \/>\n<meta name=\"twitter:site\" content=\"@info_enaw\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"nina.b\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/enaw.ch\\\/fr\\\/une-belle-mecanique-energetique#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/enaw.ch\\\/fr\\\/une-belle-mecanique-energetique\"},\"author\":{\"name\":\"nina.b\",\"@id\":\"https:\\\/\\\/enaw.ch\\\/#\\\/schema\\\/person\\\/93cfeca1794e265f49769ffda2a0797f\"},\"headline\":\"UNE BELLE M\u00c9CANIQUE \u00c9NERG\u00c9TIQUE\",\"datePublished\":\"2022-05-04T12:54:00+00:00\",\"dateModified\":\"2023-08-24T06:31:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/enaw.ch\\\/fr\\\/une-belle-mecanique-energetique\"},\"wordCount\":771,\"publisher\":{\"@id\":\"https:\\\/\\\/enaw.ch\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/enaw.ch\\\/fr\\\/une-belle-mecanique-energetique#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/enaw.ch\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/enaw_header_breitling_22.png\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/enaw.ch\\\/fr\\\/une-belle-mecanique-energetique\",\"url\":\"https:\\\/\\\/enaw.ch\\\/fr\\\/une-belle-mecanique-energetique\",\"name\":\"UNE BELLE M\u00c9CANIQUE \u00c9NERG\u00c9TIQUE | Agence de l\u2019\u00e9nergie pour l\u2019\u00e9conomie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/enaw.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/enaw.ch\\\/fr\\\/une-belle-mecanique-energetique#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/enaw.ch\\\/fr\\\/une-belle-mecanique-energetique#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/enaw.ch\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/enaw_header_breitling_22.png\",\"datePublished\":\"2022-05-04T12:54:00+00:00\",\"dateModified\":\"2023-08-24T06:31:06+00:00\",\"description\":\"Seit 2001 setzen wir gemeinsam mit den Unternehmen auf wirtschaftlichen Klimaschutz. Wir bieten individuelle L\u00f6sungen, um die Energie- und Ressourceneffizienz kontinuierlich zu steigern. Unsere 126 EnAW-Beraterinnen und EnAW-Berater kennen sich in allen Branchen und Wirtschaftszweigen aus und begleiten auch Ihr Unternehmen kompetent auf dem Weg zu weniger CO2, tieferen Kosten und mehr Energie- und Ressourceneffizienz.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/enaw.ch\\\/fr\\\/une-belle-mecanique-energetique#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/enaw.ch\\\/fr\\\/une-belle-mecanique-energetique\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/enaw.ch\\\/fr\\\/une-belle-mecanique-energetique#primaryimage\",\"url\":\"https:\\\/\\\/enaw.ch\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/enaw_header_breitling_22.png\",\"contentUrl\":\"https:\\\/\\\/enaw.ch\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/enaw_header_breitling_22.png\",\"width\":1200,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/enaw.ch\\\/fr\\\/une-belle-mecanique-energetique#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/enaw.ch\\\/fr\\\/beispiel-seite\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UNE BELLE M\u00c9CANIQUE \u00c9NERG\u00c9TIQUE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/enaw.ch\\\/#website\",\"url\":\"https:\\\/\\\/enaw.ch\\\/\",\"name\":\"Energie-Agentur der Wirtschaft\",\"description\":\"Un autre site web WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/enaw.ch\\\/#organization\"},\"alternateName\":\"EnAW\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/enaw.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/enaw.ch\\\/#organization\",\"name\":\"EnAW Energie-Agentur der Wirtschaft\",\"alternateName\":\"EnAW\",\"url\":\"https:\\\/\\\/enaw.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/enaw.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/enaw.ch\\\/wp-content\\\/uploads\\\/Logos\\\/EnAW_Logo_DE_RGB_black-1.svg\",\"contentUrl\":\"https:\\\/\\\/enaw.ch\\\/wp-content\\\/uploads\\\/Logos\\\/EnAW_Logo_DE_RGB_black-1.svg\",\"width\":219,\"height\":38,\"caption\":\"EnAW Energie-Agentur der Wirtschaft\"},\"image\":{\"@id\":\"https:\\\/\\\/enaw.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/enaw.aenec\",\"https:\\\/\\\/x.com\\\/info_enaw\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/enaw\\\/\"],\"description\":\"Seit 2001 setzen wir gemeinsam mit den Unternehmen auf wirtschaftlichen Klimaschutz. Wir bieten individuelle L\u00f6sungen, um die Energie- und Ressourceneffizienz kontinuierlich zu steigern. Unsere 126 EnAW-Beraterinnen und EnAW-Berater kennen sich in allen Branchen und Wirtschaftszweigen aus und begleiten auch Ihr Unternehmen kompetent auf dem Weg zu weniger CO2, tieferen Kosten und mehr Energie- und Ressourceneffizienz.\",\"email\":\"news@enaw.ch\",\"telephone\":\"+41 44 388 24 24\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/enaw.ch\\\/#\\\/schema\\\/person\\\/93cfeca1794e265f49769ffda2a0797f\",\"name\":\"nina.b\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f8f9c36083752c894cabe5f86c52dc120108eb6dd14d42de03a06825fb02408f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f8f9c36083752c894cabe5f86c52dc120108eb6dd14d42de03a06825fb02408f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f8f9c36083752c894cabe5f86c52dc120108eb6dd14d42de03a06825fb02408f?s=96&d=mm&r=g\",\"caption\":\"nina.b\"},\"url\":\"https:\\\/\\\/enaw.ch\\\/fr\\\/author\\\/nina-b\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"UNE BELLE M\u00c9CANIQUE \u00c9NERG\u00c9TIQUE | Agence de l\u2019\u00e9nergie pour l\u2019\u00e9conomie","description":"Seit 2001 setzen wir gemeinsam mit den Unternehmen auf wirtschaftlichen Klimaschutz. Wir bieten individuelle L\u00f6sungen, um die Energie- und Ressourceneffizienz kontinuierlich zu steigern. Unsere 126 EnAW-Beraterinnen und EnAW-Berater kennen sich in allen Branchen und Wirtschaftszweigen aus und begleiten auch Ihr Unternehmen kompetent auf dem Weg zu weniger CO2, tieferen Kosten und mehr Energie- und Ressourceneffizienz.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/enaw.ch\/fr\/une-belle-mecanique-energetique","og_locale":"fr_FR","og_type":"article","og_title":"UNE BELLE M\u00c9CANIQUE \u00c9NERG\u00c9TIQUE","og_description":"Seit 2001 setzen wir gemeinsam mit den Unternehmen auf wirtschaftlichen Klimaschutz. Wir bieten individuelle L\u00f6sungen, um die Energie- und Ressourceneffizienz kontinuierlich zu steigern. Unsere 126 EnAW-Beraterinnen und EnAW-Berater kennen sich in allen Branchen und Wirtschaftszweigen aus und begleiten auch Ihr Unternehmen kompetent auf dem Weg zu weniger CO2, tieferen Kosten und mehr Energie- und Ressourceneffizienz.","og_url":"https:\/\/enaw.ch\/fr\/une-belle-mecanique-energetique","og_site_name":"Agence de l\u2019\u00e9nergie pour l\u2019\u00e9conomie","article_publisher":"https:\/\/www.facebook.com\/enaw.aenec","article_published_time":"2022-05-04T12:54:00+00:00","article_modified_time":"2023-08-24T06:31:06+00:00","og_image":[{"url":"https:\/\/enaw.ch\/wp-content\/uploads\/2022\/05\/enaw_header_breitling_22-600x200.png","type":"image\/png","width":"","height":""}],"author":"nina.b","twitter_card":"summary_large_image","twitter_creator":"@info_enaw","twitter_site":"@info_enaw","twitter_misc":{"\u00c9crit par":"nina.b","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/enaw.ch\/fr\/une-belle-mecanique-energetique#article","isPartOf":{"@id":"https:\/\/enaw.ch\/fr\/une-belle-mecanique-energetique"},"author":{"name":"nina.b","@id":"https:\/\/enaw.ch\/#\/schema\/person\/93cfeca1794e265f49769ffda2a0797f"},"headline":"UNE BELLE M\u00c9CANIQUE \u00c9NERG\u00c9TIQUE","datePublished":"2022-05-04T12:54:00+00:00","dateModified":"2023-08-24T06:31:06+00:00","mainEntityOfPage":{"@id":"https:\/\/enaw.ch\/fr\/une-belle-mecanique-energetique"},"wordCount":771,"publisher":{"@id":"https:\/\/enaw.ch\/#organization"},"image":{"@id":"https:\/\/enaw.ch\/fr\/une-belle-mecanique-energetique#primaryimage"},"thumbnailUrl":"https:\/\/enaw.ch\/wp-content\/uploads\/2022\/05\/enaw_header_breitling_22.png","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/enaw.ch\/fr\/une-belle-mecanique-energetique","url":"https:\/\/enaw.ch\/fr\/une-belle-mecanique-energetique","name":"UNE BELLE M\u00c9CANIQUE \u00c9NERG\u00c9TIQUE | Agence de l\u2019\u00e9nergie pour l\u2019\u00e9conomie","isPartOf":{"@id":"https:\/\/enaw.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/enaw.ch\/fr\/une-belle-mecanique-energetique#primaryimage"},"image":{"@id":"https:\/\/enaw.ch\/fr\/une-belle-mecanique-energetique#primaryimage"},"thumbnailUrl":"https:\/\/enaw.ch\/wp-content\/uploads\/2022\/05\/enaw_header_breitling_22.png","datePublished":"2022-05-04T12:54:00+00:00","dateModified":"2023-08-24T06:31:06+00:00","description":"Seit 2001 setzen wir gemeinsam mit den Unternehmen auf wirtschaftlichen Klimaschutz. Wir bieten individuelle L\u00f6sungen, um die Energie- und Ressourceneffizienz kontinuierlich zu steigern. Unsere 126 EnAW-Beraterinnen und EnAW-Berater kennen sich in allen Branchen und Wirtschaftszweigen aus und begleiten auch Ihr Unternehmen kompetent auf dem Weg zu weniger CO2, tieferen Kosten und mehr Energie- und Ressourceneffizienz.","breadcrumb":{"@id":"https:\/\/enaw.ch\/fr\/une-belle-mecanique-energetique#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/enaw.ch\/fr\/une-belle-mecanique-energetique"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/enaw.ch\/fr\/une-belle-mecanique-energetique#primaryimage","url":"https:\/\/enaw.ch\/wp-content\/uploads\/2022\/05\/enaw_header_breitling_22.png","contentUrl":"https:\/\/enaw.ch\/wp-content\/uploads\/2022\/05\/enaw_header_breitling_22.png","width":1200,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/enaw.ch\/fr\/une-belle-mecanique-energetique#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/enaw.ch\/fr\/beispiel-seite"},{"@type":"ListItem","position":2,"name":"UNE BELLE M\u00c9CANIQUE \u00c9NERG\u00c9TIQUE"}]},{"@type":"WebSite","@id":"https:\/\/enaw.ch\/#website","url":"https:\/\/enaw.ch\/","name":"Energie-Agentur der Wirtschaft","description":"Un autre site web WordPress","publisher":{"@id":"https:\/\/enaw.ch\/#organization"},"alternateName":"EnAW","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/enaw.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/enaw.ch\/#organization","name":"EnAW Energie-Agentur der Wirtschaft","alternateName":"EnAW","url":"https:\/\/enaw.ch\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/enaw.ch\/#\/schema\/logo\/image\/","url":"https:\/\/enaw.ch\/wp-content\/uploads\/Logos\/EnAW_Logo_DE_RGB_black-1.svg","contentUrl":"https:\/\/enaw.ch\/wp-content\/uploads\/Logos\/EnAW_Logo_DE_RGB_black-1.svg","width":219,"height":38,"caption":"EnAW Energie-Agentur der Wirtschaft"},"image":{"@id":"https:\/\/enaw.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/enaw.aenec","https:\/\/x.com\/info_enaw","https:\/\/www.linkedin.com\/company\/enaw\/"],"description":"Seit 2001 setzen wir gemeinsam mit den Unternehmen auf wirtschaftlichen Klimaschutz. Wir bieten individuelle L\u00f6sungen, um die Energie- und Ressourceneffizienz kontinuierlich zu steigern. Unsere 126 EnAW-Beraterinnen und EnAW-Berater kennen sich in allen Branchen und Wirtschaftszweigen aus und begleiten auch Ihr Unternehmen kompetent auf dem Weg zu weniger CO2, tieferen Kosten und mehr Energie- und Ressourceneffizienz.","email":"news@enaw.ch","telephone":"+41 44 388 24 24"},{"@type":"Person","@id":"https:\/\/enaw.ch\/#\/schema\/person\/93cfeca1794e265f49769ffda2a0797f","name":"nina.b","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/f8f9c36083752c894cabe5f86c52dc120108eb6dd14d42de03a06825fb02408f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f8f9c36083752c894cabe5f86c52dc120108eb6dd14d42de03a06825fb02408f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f8f9c36083752c894cabe5f86c52dc120108eb6dd14d42de03a06825fb02408f?s=96&d=mm&r=g","caption":"nina.b"},"url":"https:\/\/enaw.ch\/fr\/author\/nina-b"}]}},"_links":{"self":[{"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/posts\/6677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/comments?post=6677"}],"version-history":[{"count":0,"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/posts\/6677\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/media\/10690"}],"wp:attachment":[{"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/media?parent=6677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/categories?post=6677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/tags?post=6677"},{"taxonomy":"kanton","embeddable":true,"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/kanton?post=6677"},{"taxonomy":"thema","embeddable":true,"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/thema?post=6677"},{"taxonomy":"produkt","embeddable":true,"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/produkt?post=6677"},{"taxonomy":"rubrik","embeddable":true,"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/rubrik?post=6677"},{"taxonomy":"branche","embeddable":true,"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/branche?post=6677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}