{"id":11068,"date":"2022-05-31T09:53:10","date_gmt":"2022-05-31T07:53:10","guid":{"rendered":"https:\/\/enaw.ch\/impressum\/"},"modified":"2023-01-13T13:07:30","modified_gmt":"2023-01-13T12:07:30","slug":"impressum","status":"publish","type":"page","link":"https:\/\/enaw.ch\/fr\/impressum","title":{"rendered":"Impressum"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Exploitant du site<\/strong><br>Agence de l\u2019\u00e9nergie pour l\u2019\u00e9conomie (AEnEC)<br>Cr\u00eat 108a<br>2314 La Sagne<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>R\u00e9alisation<\/strong><br>BERTA Kommunikation AG<br>Bertastrasse 1<br>8003 Zurich<br><a href=\"https:\/\/berta-kommunikation.ch\/\">www.berta-kommunikation.ch<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>H\u00e9bergement<\/strong><br>cyon GmbH<br>Aeschengraben 6<br>CH-4051 Basel<br><a href=\"http:\/\/www.cyon.ch\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.cyon.ch<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Exploitant du siteAgence de l\u2019\u00e9nergie pour l\u2019\u00e9conomie (AEnEC)Cr\u00eat 108a2314 La Sagne R\u00e9alisationBERTA Kommunikation AGBertastrasse 18003 Zurichwww.berta-kommunikation.ch H\u00e9bergementcyon GmbHAeschengraben 6CH-4051 Baselwww.cyon.ch<\/p>\n","protected":false},"author":1,"featured_media":6040,"parent":0,"menu_order":37,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-11068","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Impressum | Agence de l\u2019\u00e9nergie pour l\u2019\u00e9conomie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/enaw.ch\/fr\/impressum\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Impressum\" \/>\n<meta property=\"og:description\" content=\"Exploitant du siteAgence de l\u2019\u00e9nergie pour l\u2019\u00e9conomie (AEnEC)Cr\u00eat 108a2314 La Sagne R\u00e9alisationBERTA Kommunikation AGBertastrasse 18003 Zurichwww.berta-kommunikation.ch H\u00e9bergementcyon GmbHAeschengraben 6CH-4051 Baselwww.cyon.ch\" \/>\n<meta property=\"og:url\" content=\"https:\/\/enaw.ch\/fr\/impressum\" \/>\n<meta property=\"og:site_name\" content=\"Agence de l\u2019\u00e9nergie pour l\u2019\u00e9conomie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/enaw.aenec\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-13T12:07:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/enaw.ch\/wp-content\/uploads\/2022\/05\/enaw_header_energie-modell_2-600x200.png\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@info_enaw\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/enaw.ch\\\/fr\\\/impressum\",\"url\":\"https:\\\/\\\/enaw.ch\\\/fr\\\/impressum\",\"name\":\"Impressum | Agence de l\u2019\u00e9nergie pour l\u2019\u00e9conomie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/enaw.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/enaw.ch\\\/fr\\\/impressum#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/enaw.ch\\\/fr\\\/impressum#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/enaw.ch\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/enaw_header_energie-modell_2.png\",\"datePublished\":\"2022-05-31T07:53:10+00:00\",\"dateModified\":\"2023-01-13T12:07:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/enaw.ch\\\/fr\\\/impressum#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/enaw.ch\\\/fr\\\/impressum\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/enaw.ch\\\/fr\\\/impressum#primaryimage\",\"url\":\"https:\\\/\\\/enaw.ch\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/enaw_header_energie-modell_2.png\",\"contentUrl\":\"https:\\\/\\\/enaw.ch\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/enaw_header_energie-modell_2.png\",\"width\":1200,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/enaw.ch\\\/fr\\\/impressum#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/enaw.ch\\\/fr\\\/beispiel-seite\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Impressum\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/enaw.ch\\\/#website\",\"url\":\"https:\\\/\\\/enaw.ch\\\/\",\"name\":\"Energie-Agentur der Wirtschaft\",\"description\":\"Un autre site web WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/enaw.ch\\\/#organization\"},\"alternateName\":\"EnAW\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/enaw.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/enaw.ch\\\/#organization\",\"name\":\"EnAW Energie-Agentur der Wirtschaft\",\"alternateName\":\"EnAW\",\"url\":\"https:\\\/\\\/enaw.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/enaw.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/enaw.ch\\\/wp-content\\\/uploads\\\/Logos\\\/EnAW_Logo_DE_RGB_black-1.svg\",\"contentUrl\":\"https:\\\/\\\/enaw.ch\\\/wp-content\\\/uploads\\\/Logos\\\/EnAW_Logo_DE_RGB_black-1.svg\",\"width\":219,\"height\":38,\"caption\":\"EnAW Energie-Agentur der Wirtschaft\"},\"image\":{\"@id\":\"https:\\\/\\\/enaw.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/enaw.aenec\",\"https:\\\/\\\/x.com\\\/info_enaw\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/enaw\\\/\"],\"description\":\"Seit 2001 setzen wir gemeinsam mit den Unternehmen auf wirtschaftlichen Klimaschutz. Wir bieten individuelle L\u00f6sungen, um die Energie- und Ressourceneffizienz kontinuierlich zu steigern. Unsere 126 EnAW-Beraterinnen und EnAW-Berater kennen sich in allen Branchen und Wirtschaftszweigen aus und begleiten auch Ihr Unternehmen kompetent auf dem Weg zu weniger CO2, tieferen Kosten und mehr Energie- und Ressourceneffizienz.\",\"email\":\"news@enaw.ch\",\"telephone\":\"+41 44 388 24 24\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Impressum | Agence de l\u2019\u00e9nergie pour l\u2019\u00e9conomie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/enaw.ch\/fr\/impressum","og_locale":"fr_FR","og_type":"article","og_title":"Impressum","og_description":"Exploitant du siteAgence de l\u2019\u00e9nergie pour l\u2019\u00e9conomie (AEnEC)Cr\u00eat 108a2314 La Sagne R\u00e9alisationBERTA Kommunikation AGBertastrasse 18003 Zurichwww.berta-kommunikation.ch H\u00e9bergementcyon GmbHAeschengraben 6CH-4051 Baselwww.cyon.ch","og_url":"https:\/\/enaw.ch\/fr\/impressum","og_site_name":"Agence de l\u2019\u00e9nergie pour l\u2019\u00e9conomie","article_publisher":"https:\/\/www.facebook.com\/enaw.aenec","article_modified_time":"2023-01-13T12:07:30+00:00","og_image":[{"url":"https:\/\/enaw.ch\/wp-content\/uploads\/2022\/05\/enaw_header_energie-modell_2-600x200.png","type":"image\/png","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@info_enaw","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/enaw.ch\/fr\/impressum","url":"https:\/\/enaw.ch\/fr\/impressum","name":"Impressum | Agence de l\u2019\u00e9nergie pour l\u2019\u00e9conomie","isPartOf":{"@id":"https:\/\/enaw.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/enaw.ch\/fr\/impressum#primaryimage"},"image":{"@id":"https:\/\/enaw.ch\/fr\/impressum#primaryimage"},"thumbnailUrl":"https:\/\/enaw.ch\/wp-content\/uploads\/2022\/05\/enaw_header_energie-modell_2.png","datePublished":"2022-05-31T07:53:10+00:00","dateModified":"2023-01-13T12:07:30+00:00","breadcrumb":{"@id":"https:\/\/enaw.ch\/fr\/impressum#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/enaw.ch\/fr\/impressum"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/enaw.ch\/fr\/impressum#primaryimage","url":"https:\/\/enaw.ch\/wp-content\/uploads\/2022\/05\/enaw_header_energie-modell_2.png","contentUrl":"https:\/\/enaw.ch\/wp-content\/uploads\/2022\/05\/enaw_header_energie-modell_2.png","width":1200,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/enaw.ch\/fr\/impressum#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/enaw.ch\/fr\/beispiel-seite"},{"@type":"ListItem","position":2,"name":"Impressum"}]},{"@type":"WebSite","@id":"https:\/\/enaw.ch\/#website","url":"https:\/\/enaw.ch\/","name":"Energie-Agentur der Wirtschaft","description":"Un autre site web WordPress","publisher":{"@id":"https:\/\/enaw.ch\/#organization"},"alternateName":"EnAW","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/enaw.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/enaw.ch\/#organization","name":"EnAW Energie-Agentur der Wirtschaft","alternateName":"EnAW","url":"https:\/\/enaw.ch\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/enaw.ch\/#\/schema\/logo\/image\/","url":"https:\/\/enaw.ch\/wp-content\/uploads\/Logos\/EnAW_Logo_DE_RGB_black-1.svg","contentUrl":"https:\/\/enaw.ch\/wp-content\/uploads\/Logos\/EnAW_Logo_DE_RGB_black-1.svg","width":219,"height":38,"caption":"EnAW Energie-Agentur der Wirtschaft"},"image":{"@id":"https:\/\/enaw.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/enaw.aenec","https:\/\/x.com\/info_enaw","https:\/\/www.linkedin.com\/company\/enaw\/"],"description":"Seit 2001 setzen wir gemeinsam mit den Unternehmen auf wirtschaftlichen Klimaschutz. Wir bieten individuelle L\u00f6sungen, um die Energie- und Ressourceneffizienz kontinuierlich zu steigern. Unsere 126 EnAW-Beraterinnen und EnAW-Berater kennen sich in allen Branchen und Wirtschaftszweigen aus und begleiten auch Ihr Unternehmen kompetent auf dem Weg zu weniger CO2, tieferen Kosten und mehr Energie- und Ressourceneffizienz.","email":"news@enaw.ch","telephone":"+41 44 388 24 24"}]}},"_links":{"self":[{"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/pages\/11068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/comments?post=11068"}],"version-history":[{"count":0,"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/pages\/11068\/revisions"}],"wp:attachment":[{"href":"https:\/\/enaw.ch\/fr\/wp-json\/wp\/v2\/media?parent=11068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}